{"id":82617,"date":"2026-07-15T10:23:37","date_gmt":"2026-07-15T10:23:37","guid":{"rendered":"https:\/\/lobosnews.com.ar\/?p=82617"},"modified":"2026-07-15T12:07:44","modified_gmt":"2026-07-15T12:07:44","slug":"dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina","status":"publish","type":"post","link":"https:\/\/lobosnews.com.ar\/index.php\/2026\/07\/15\/dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina\/","title":{"rendered":"Dura critica a una figura de Francia tras la eliminaci\u00f3n del Mundial: \u201cLo sentaban en la mesa de Zidane y Platini y no est\u00e1 ni en la cocina\u201d"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/07\/dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina.jpg\" alt=\"La prensa francesa carg\u00f3 contra Olise tras la derrota frente a Espa\u00f1a (Reuters)\" height=\"2860\" width=\"4193\"\/><\/p>\n<p>En el programa <i>After Foot<\/i> de <i>RMC<\/i>, el reconocido periodista franc\u00e9s <b>Daniel Riolo<\/b> expres\u00f3 un fuerte descontento tras<span class=\"waslinkname\"> la eliminaci\u00f3n de la selecci\u00f3n en la semifinal del <b>Mundial 2026<\/b><\/span> frente a <b>Espa\u00f1a<\/b>. Su blanco principal fue <b>Michael Olise<\/b>, a quien <b>se\u00f1al\u00f3 directamente <\/b>por el bajo rendimiento que mostr\u00f3 en uno de los momentos m\u00e1s decisivos del torneo. Seg\u00fan el analista, la actuaci\u00f3n del mediapunta del <b>Bayern de M\u00fanich<\/b> qued\u00f3 lejos de las expectativas que hab\u00eda generado en el inicio del certamen.<\/p>\n<p>Seg\u00fan inform\u00f3 <i>RMC<\/i>, \u201cEst\u00e1bamos todos borrachos. Olise y Mbapp\u00e9 formaban la mejor dupla que hab\u00edamos tenido en la historia de<i> Les Bleus<\/i>. <b>A Olise lo sentaban a la mesa con Zidane y Platini cuando ahora mismo ni siquiera est\u00e1 en la cocina\u201d<\/b>, critic\u00f3 <b>Riolo<\/b> durante la transmisi\u00f3n posterior al partido. Las palabras del periodista reflejaron el ambiente de decepci\u00f3n que reinaba en el entorno franc\u00e9s tras la derrota por 2-0. El comentario alud\u00eda a la comparaci\u00f3n que se hab\u00eda hecho d\u00edas atr\u00e1s entre <b>Olise<\/b> y leyendas del f\u00fatbol galo, como <b>Michel Platini<\/b> y <b>Zinedine Zidane<\/b>.<\/p>\n<p>En el mismo programa, <b>Riolo<\/b> profundiz\u00f3 su visi\u00f3n sobre el desempe\u00f1o del futbolista: <b>\u201cLo que ha hecho desde el inicio de la competici\u00f3n, lo ha hecho porque ten\u00eda espacio y comodidad.<\/b> La comodidad para dar pases y organizarse. Desde que hubo m\u00e1s presi\u00f3n en el centro del campo, cuando le lleg\u00f3 m\u00e1s r\u00e1pido, nos dimos cuenta de nuevo de que el rol de n\u00famero 10 ya no existe en el f\u00fatbol actual\u201d, sostuvo el comentarista. De acuerdo con su an\u00e1lisis, el contexto del partido y la presi\u00f3n ejercida por el mediocampo espa\u00f1ol <b>expusieron las limitaciones de Olise<\/b>, quien hasta ese momento hab\u00eda destacado por su precisi\u00f3n y capacidad de asistencia.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/07\/dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina-1.jpg\" alt=\"Francia cay\u00f3 2-0 en la semifinal del Mundial (AFP)\" height=\"4000\" width=\"6000\"\/><\/p>\n<p>El desempe\u00f1o de <b>Olise<\/b> en la semifinal contrast\u00f3 con las expectativas construidas a lo largo del torneo. El jugador, que hasta ese momento acumulaba cinco asistencias y se hab\u00eda convertido en el m\u00e1ximo asistente de la Copa del Mundo, <b>vio limitada su influencia por la organizaci\u00f3n defensiva de Espa\u00f1a<\/b> y un arquero s\u00f3lido bajo los tres palos. Seg\u00fan <i>RMC<\/i>, en el partido disputado en <b>Dallas<\/b>, el mediapunta perdi\u00f3 el bal\u00f3n en 20 ocasiones y no logr\u00f3 completar regates, siendo superado por la marca de <b>Rodri<\/b>. La tensi\u00f3n acumulada se reflej\u00f3 en una entrada peligrosa que casi le cuesta una expulsi\u00f3n en el comienzo del encuentro, antes de ser reemplazado en el minuto 72.<\/p>\n<p>La frustraci\u00f3n expresada por <b>Riolo<\/b> cobr\u00f3 mayor dimensi\u00f3n al recordar el contexto previo al partido, cuando la ex figura de la selecci\u00f3n francesa y actual t\u00e9cnico <b>Patrick Vieira<\/b> hab\u00eda elogiado abiertamente a <b>Olise<\/b> en declaraciones a <i>ITV Football<\/i>: <b>\u201cTuvimos a Michel Platini y a Zinedine Zidane, y ahora creo firmemente que tenemos a Michael Olise. Es un futuro ganador del Bal\u00f3n de Oro con todas las cualidades para brillar en los grandes escenarios\u201d<\/b>, afirm\u00f3 <b>Vieira<\/b> tras el cierre de la temporada europea. El t\u00e9cnico destac\u00f3 tambi\u00e9n la visi\u00f3n de juego y la calidad de los pases del futbolista en el <b>Bayern de M\u00fanich<\/b>, club donde registr\u00f3 22 goles y 31 asistencias en 52 partidos oficiales.<\/p>\n<p>La eliminaci\u00f3n de <b>Francia<\/b> en el Mundial 2026 marc\u00f3 el final de una campa\u00f1a que comenz\u00f3 con un ataque letal, pero que<b> perdi\u00f3 fuerza en las \u00faltimas instancias.<\/b> El equipo de <b>Didier Deschamps<\/b> no logr\u00f3 generar situaciones de peligro ante una Espa\u00f1a que neutraliz\u00f3 a sus principales figuras, entre ellas <b>Kylian Mbapp\u00e9<\/b> y <b>Ousmane Demb\u00e9l\u00e9<\/b>, quienes tampoco lograron desbordar ni romper la presi\u00f3n rival.<\/p>\n<p>El futuro de <b>Olise<\/b> y de la selecci\u00f3n de <b>Francia<\/b> qued\u00f3 bajo escrutinio tras la eliminaci\u00f3n. La atenci\u00f3n medi\u00e1tica ahora no solo se centra en el desempe\u00f1o de sus figuras, sino tambi\u00e9n en eventuales cambios en el cuerpo t\u00e9cnico, en donde el nombre de <b>Zinedine Zidane<\/b> comenz\u00f3 a tomar fuerza para reemplazar a Deschamps despu\u00e9s de una buena campa\u00f1a en la que conquist\u00f3 una Copa del Mundo (2018), adem\u00e1s de alcanzar una final (2022) y una semifinal (2026) .<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el programa After Foot de RMC, el reconocido periodista franc\u00e9s Daniel Riolo expres\u00f3 un fuerte descontento tras la eliminaci\u00f3n de la selecci\u00f3n en la semifinal del Mundial 2026 frente a Espa\u00f1a. Su blanco principal fue Michael Olise, a quien se\u00f1al\u00f3 directamente por el bajo rendimiento que mostr\u00f3 en uno de los momentos m\u00e1s decisivos&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[30],"tags":[39],"class_list":["post-82617","post","type-post","status-publish","format-standard","hentry","category-argentina","tag-deportes"],"magazineBlocksPostFeaturedMedia":{"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"newsmatic-featured":false,"newsmatic-list":false,"newsmatic-thumb":false,"newsmatic-small":false,"newsmatic-grid":false},"magazineBlocksPostAuthor":{"name":"admin","avatar":"https:\/\/secure.gravatar.com\/avatar\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":"0","magazineBlocksPostExcerpt":"En el programa After Foot de RMC, el reconocido periodista franc\u00e9s Daniel Riolo expres\u00f3 un fuerte descontento tras la eliminaci\u00f3n de la selecci\u00f3n en la semifinal del Mundial 2026 frente a Espa\u00f1a. Su blanco principal fue Michael Olise, a quien se\u00f1al\u00f3 directamente por el bajo rendimiento que mostr\u00f3 en uno de los momentos m\u00e1s decisivos...","magazineBlocksPostCategories":["Argentina"],"magazineBlocksPostViewCount":4,"magazineBlocksPostReadTime":4,"magazine_blocks_featured_image_url":{"full":false,"medium":false,"thumbnail":false},"magazine_blocks_author":{"display_name":"admin","author_link":"https:\/\/lobosnews.com.ar\/index.php\/author\/lobos-news\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-30\">Argentina<\/a>","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dura critica a una figura de Francia tras la eliminaci\u00f3n del Mundial: \u201cLo sentaban en la mesa de Zidane y Platini y no est\u00e1 ni en la cocina\u201d - Lobos News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lobosnews.com.ar\/index.php\/2026\/07\/15\/dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dura critica a una figura de Francia tras la eliminaci\u00f3n del Mundial: \u201cLo sentaban en la mesa de Zidane y Platini y no est\u00e1 ni en la cocina\u201d - Lobos News\" \/>\n<meta property=\"og:description\" content=\"En el programa After Foot de RMC, el reconocido periodista franc\u00e9s Daniel Riolo expres\u00f3 un fuerte descontento tras la eliminaci\u00f3n de la selecci\u00f3n en la semifinal del Mundial 2026 frente a Espa\u00f1a. Su blanco principal fue Michael Olise, a quien se\u00f1al\u00f3 directamente por el bajo rendimiento que mostr\u00f3 en uno de los momentos m\u00e1s decisivos...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lobosnews.com.ar\/index.php\/2026\/07\/15\/dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina\/\" \/>\n<meta property=\"og:site_name\" content=\"Lobos News\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T10:23:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T12:07:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/07\/dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina.jpg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/index.php\\\/2026\\\/07\\\/15\\\/dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/index.php\\\/2026\\\/07\\\/15\\\/dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/#\\\/schema\\\/person\\\/232422a593d5c541dd9aef6aaed10943\"},\"headline\":\"Dura critica a una figura de Francia tras la eliminaci\u00f3n del Mundial: \u201cLo sentaban en la mesa de Zidane y Platini y no est\u00e1 ni en la cocina\u201d\",\"datePublished\":\"2026-07-15T10:23:37+00:00\",\"dateModified\":\"2026-07-15T12:07:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/index.php\\\/2026\\\/07\\\/15\\\/dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina\\\/\"},\"wordCount\":746,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/index.php\\\/2026\\\/07\\\/15\\\/dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lobosnews.com.ar\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina.jpg\",\"keywords\":[\"Deportes\"],\"articleSection\":[\"Argentina\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lobosnews.com.ar\\\/index.php\\\/2026\\\/07\\\/15\\\/dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/index.php\\\/2026\\\/07\\\/15\\\/dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina\\\/\",\"url\":\"https:\\\/\\\/lobosnews.com.ar\\\/index.php\\\/2026\\\/07\\\/15\\\/dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina\\\/\",\"name\":\"Dura critica a una figura de Francia tras la eliminaci\u00f3n del Mundial: \u201cLo sentaban en la mesa de Zidane y Platini y no est\u00e1 ni en la cocina\u201d - Lobos News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/index.php\\\/2026\\\/07\\\/15\\\/dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/index.php\\\/2026\\\/07\\\/15\\\/dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lobosnews.com.ar\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina.jpg\",\"datePublished\":\"2026-07-15T10:23:37+00:00\",\"dateModified\":\"2026-07-15T12:07:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/index.php\\\/2026\\\/07\\\/15\\\/dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lobosnews.com.ar\\\/index.php\\\/2026\\\/07\\\/15\\\/dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/index.php\\\/2026\\\/07\\\/15\\\/dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lobosnews.com.ar\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/lobosnews.com.ar\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina-scaled.jpg\",\"width\":2560,\"height\":1746},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/index.php\\\/2026\\\/07\\\/15\\\/dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/lobosnews.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dura critica a una figura de Francia tras la eliminaci\u00f3n del Mundial: \u201cLo sentaban en la mesa de Zidane y Platini y no est\u00e1 ni en la cocina\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/lobosnews.com.ar\\\/\",\"name\":\"Lobos News\",\"description\":\"Informaci\u00f3n a cada instante\",\"publisher\":{\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lobosnews.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/#organization\",\"name\":\"Lobos News\",\"url\":\"https:\\\/\\\/lobosnews.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lobosnews.com.ar\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logo-lobosnews.png\",\"contentUrl\":\"https:\\\/\\\/lobosnews.com.ar\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logo-lobosnews.png\",\"width\":500,\"height\":200,\"caption\":\"Lobos News\"},\"image\":{\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/#\\\/schema\\\/person\\\/232422a593d5c541dd9aef6aaed10943\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/lobosnews.com.ar\"],\"url\":\"https:\\\/\\\/lobosnews.com.ar\\\/index.php\\\/author\\\/lobos-news\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dura critica a una figura de Francia tras la eliminaci\u00f3n del Mundial: \u201cLo sentaban en la mesa de Zidane y Platini y no est\u00e1 ni en la cocina\u201d - Lobos News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lobosnews.com.ar\/index.php\/2026\/07\/15\/dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina\/","og_locale":"es_ES","og_type":"article","og_title":"Dura critica a una figura de Francia tras la eliminaci\u00f3n del Mundial: \u201cLo sentaban en la mesa de Zidane y Platini y no est\u00e1 ni en la cocina\u201d - Lobos News","og_description":"En el programa After Foot de RMC, el reconocido periodista franc\u00e9s Daniel Riolo expres\u00f3 un fuerte descontento tras la eliminaci\u00f3n de la selecci\u00f3n en la semifinal del Mundial 2026 frente a Espa\u00f1a. Su blanco principal fue Michael Olise, a quien se\u00f1al\u00f3 directamente por el bajo rendimiento que mostr\u00f3 en uno de los momentos m\u00e1s decisivos...","og_url":"https:\/\/lobosnews.com.ar\/index.php\/2026\/07\/15\/dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina\/","og_site_name":"Lobos News","article_published_time":"2026-07-15T10:23:37+00:00","article_modified_time":"2026-07-15T12:07:44+00:00","og_image":[{"url":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/07\/dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina.jpg","type":"","width":"","height":""}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/07\/15\/dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina\/#article","isPartOf":{"@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/07\/15\/dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina\/"},"author":{"name":"admin","@id":"https:\/\/lobosnews.com.ar\/#\/schema\/person\/232422a593d5c541dd9aef6aaed10943"},"headline":"Dura critica a una figura de Francia tras la eliminaci\u00f3n del Mundial: \u201cLo sentaban en la mesa de Zidane y Platini y no est\u00e1 ni en la cocina\u201d","datePublished":"2026-07-15T10:23:37+00:00","dateModified":"2026-07-15T12:07:44+00:00","mainEntityOfPage":{"@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/07\/15\/dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina\/"},"wordCount":746,"commentCount":0,"publisher":{"@id":"https:\/\/lobosnews.com.ar\/#organization"},"image":{"@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/07\/15\/dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina\/#primaryimage"},"thumbnailUrl":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/07\/dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina.jpg","keywords":["Deportes"],"articleSection":["Argentina"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lobosnews.com.ar\/index.php\/2026\/07\/15\/dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/07\/15\/dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina\/","url":"https:\/\/lobosnews.com.ar\/index.php\/2026\/07\/15\/dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina\/","name":"Dura critica a una figura de Francia tras la eliminaci\u00f3n del Mundial: \u201cLo sentaban en la mesa de Zidane y Platini y no est\u00e1 ni en la cocina\u201d - Lobos News","isPartOf":{"@id":"https:\/\/lobosnews.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/07\/15\/dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina\/#primaryimage"},"image":{"@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/07\/15\/dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina\/#primaryimage"},"thumbnailUrl":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/07\/dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina.jpg","datePublished":"2026-07-15T10:23:37+00:00","dateModified":"2026-07-15T12:07:44+00:00","breadcrumb":{"@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/07\/15\/dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lobosnews.com.ar\/index.php\/2026\/07\/15\/dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/07\/15\/dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina\/#primaryimage","url":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/07\/dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina-scaled.jpg","contentUrl":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/07\/dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina-scaled.jpg","width":2560,"height":1746},{"@type":"BreadcrumbList","@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/07\/15\/dura-critica-a-una-figura-de-francia-tras-la-eliminacion-del-mundial-lo-sentaban-en-la-mesa-de-zidane-y-platini-y-no-esta-ni-en-la-cocina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lobosnews.com.ar\/"},{"@type":"ListItem","position":2,"name":"Dura critica a una figura de Francia tras la eliminaci\u00f3n del Mundial: \u201cLo sentaban en la mesa de Zidane y Platini y no est\u00e1 ni en la cocina\u201d"}]},{"@type":"WebSite","@id":"https:\/\/lobosnews.com.ar\/#website","url":"https:\/\/lobosnews.com.ar\/","name":"Lobos News","description":"Informaci\u00f3n a cada instante","publisher":{"@id":"https:\/\/lobosnews.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lobosnews.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/lobosnews.com.ar\/#organization","name":"Lobos News","url":"https:\/\/lobosnews.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lobosnews.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/01\/logo-lobosnews.png","contentUrl":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/01\/logo-lobosnews.png","width":500,"height":200,"caption":"Lobos News"},"image":{"@id":"https:\/\/lobosnews.com.ar\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/lobosnews.com.ar\/#\/schema\/person\/232422a593d5c541dd9aef6aaed10943","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/lobosnews.com.ar"],"url":"https:\/\/lobosnews.com.ar\/index.php\/author\/lobos-news\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/82617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=82617"}],"version-history":[{"count":1,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/82617\/revisions"}],"predecessor-version":[{"id":82620,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/82617\/revisions\/82620"}],"wp:attachment":[{"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=82617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=82617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=82617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}