{"id":82461,"date":"2026-07-15T05:22:23","date_gmt":"2026-07-15T05:22:23","guid":{"rendered":"https:\/\/lobosnews.com.ar\/?p=82461"},"modified":"2026-07-15T05:33:17","modified_gmt":"2026-07-15T05:33:17","slug":"sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion","status":"publish","type":"post","link":"https:\/\/lobosnews.com.ar\/index.php\/2026\/07\/15\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion\/","title":{"rendered":"Sufri\u00f3 como nadie a Maradona en M\u00e9xico 86, se convirti\u00f3 en \u201cvillano\u201d de Argentina y sorprendi\u00f3 con un pedido de reconciliaci\u00f3n"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/07\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion.jpg\" alt=\"Maradona esconde el pu\u00f1o para impulsar la pelota y Shilton pasa de largo: nace \"La Mano de Dios\" (Foto: Bob Thomas)\" height=\"1264\" width=\"1920\"\/><\/p>\n<p><b>Peter Shilton<\/b> puede colgarse varias medallas por su carrera e incluso en relaci\u00f3n a su vida personal. Desde sus sobrios 183 cent\u00edmetros y la seguridad de sus guantes, edific\u00f3 una trayectoria que lo llev\u00f3, por ejemplo, a<b> disputar tres Mundiales (1982, 1986 y 1990)<\/b>. O a convertirse en<b> el arquero ingl\u00e9s que disput\u00f3 mayor cantidad de partidos en la historia (1387)<\/b> hasta que se retir\u00f3 de la actividad, en 1997, a los 48 a\u00f1os. <\/p>\n<p>Tambi\u00e9n puede ostentar la presea de haber logrado doblegar a la adicci\u00f3n al juego, que lo llev\u00f3 a transitar un largo calvario del que lo ayud\u00f3 a salir su segunda esposa Stephanie Hayward, con quien se cas\u00f3 en 2015. \u201cDurante 45 a\u00f1os fui un adicto al juego. <b>Mi adicci\u00f3n casi me arruina: mental, f\u00edsica y financieramente<\/b>. <b>Ojal\u00e1 pudiera decir cu\u00e1nto perd\u00ed, pero la verdad es que no lo s\u00e9. Deben ser millones. Cuando el h\u00e1bito se volvi\u00f3 absorbente, me perd\u00ed<\/b>\u201d, lleg\u00f3 a confesar en una valiente entrevista.<\/p>\n<p>Pero la medalla m\u00e1s grande es, a la vez, la m\u00e1s lacerante. Y, seguramente, aunque suene a contradicci\u00f3n, la m\u00e1s rentable. Porque hay un r\u00f3tulo que lo persigue, por el que ha bramado ante cada micr\u00f3fono que enfrent\u00f3, pero su actitud no hizo m\u00e1s que agregarle pegamento al cartel: el de la v\u00edctima m\u00e1s c\u00e9lebre de <b>Diego Armando Maradona<\/b> en <b>el m\u00edtico triunfo de Argentina 2-1 ante Inglaterra en los cuartos de final de M\u00e9xico 86<\/b>. La Copa del Mundo 2026 le vuelve a ofrecer una revancha, con<b> Lionel Messi<\/b>, el heredero de Diego, vigente a los 39 a\u00f1os. <\/p>\n<p>Shilton, de 76 a\u00f1os, es quien queda desairado por el pu\u00f1o comedido y p\u00edcaro de <i>Pelusa<\/i>, simulando un cabezazo bombeado, en <i><b>La Mano de Dios<\/b><\/i>. Y es uno de los cinco futbolistas (junto a Beardsley, Reid, Butcher, Fenwick) a los que el astro desparram\u00f3 en <i><b>El Gol del Siglo<\/b><\/i>. De ese grupo de testigos privilegiados de la obra, es el que m\u00e1s airada y continuamente reclam\u00f3 en los \u00faltimos 40 a\u00f1os, clamando justicia. Incluso, casi una herej\u00eda, lleg\u00f3 a deslegitimar el 2-1.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/07\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion-1.jpg\" alt=\"El saludo protocolar entre los capitanes antes del \u00e9pico partido (Foto David Cannon\/Allsport)\" height=\"1079\" width=\"1920\"\/><\/p>\n<p>Pero, en un giro inesperado en una novela de casi cuatro d\u00e9cadas, pas\u00f3 de bocado a mand\u00edbula: subast\u00f3 el buzo que utiliz\u00f3 en aquella jornada hist\u00f3rica. No una prenda inyectada con gloria de sus atajadas: el valor lo imprime, precisamente, todo lo que desde\u00f1\u00f3 y busc\u00f3 contaminar a lo largo del tiempo, en un c\u00f3modo rol de villano. <\/p>\n<p>En realidad, poco pudo hacer ante la astucia -para desorientar al \u00e1rbitro tunecino <b>Ali Bin Nasser<\/b>&#8211; y la habilidad de Maradona, que hasta hab\u00eda anticipado lo que iba a suceder con un s\u00e1ndwich de mortadela en la mano. <\/p>\n<p><b>\u201cEst\u00e1bamos desayunando. Le dije \u2018vos ten\u00e9s que hacer un par de goles\u2019. Y me dijo que s\u00ed, que los iba a hacer\u201d<\/b>, le supo contar a <b>Infobae Roberto Mariani<\/b>, ayudante de campo de <b>Carlos Bilardo<\/b> en las Copas del Mundo del 86 y del 90. \u201cDiego tambi\u00e9n cont\u00f3 que hab\u00eda hablado con sus hermanos, con Lalo (Ra\u00fal) y el Turco (Hugo) de una jugada en la que \u00e9l se recostaba sobre la derecha, encaraba, dejaba rivales en el camino y defin\u00eda al segundo palo. Y entonces dijo: \u2018Tengo unas ganas de hacerle un gol de esos a los ingleses\u2019. Y bueno, un rato despu\u00e9s, de esa manera, hizo el gol de su vida\u201d, complet\u00f3.<\/p>\n<p>Lo curioso es que para Shilton, quien primero qued\u00f3 lanz\u00e1ndole un pu\u00f1etazo al cielo ante <i>La Mano de Dios<\/i>, y luego termin\u00f3 despatarrado ante el quiebre de cintura del <i>Diez<\/i>, hizo una carrera en los medios rest\u00e1ndole cr\u00e9dito a la \u00e9pica actuaci\u00f3n de su rival.<\/p>\n<p>En cuanto al primer tanto, en una entrevista con <i>The Guardian<\/i>, asever\u00f3: \u201c<b>Hice todo lo que pude y en la famosa foto se ve que yo estoy m\u00e1s cerca de la pelota que su cabeza. Por eso \u00e9l la toca con la mano<\/b>. Siempre habr\u00e1 gente que diga \u2018Ey, \u00e9l salt\u00f3 m\u00e1s que vos\u2019. Pero no, <b>\u00e9l hizo trampa<\/b>\u201d. En dicha conquista, el reglamento lo respalda, m\u00e1s all\u00e1 de la historia juzgada. Ahora bien, \u00bfcu\u00e1l fue la excusa para el segundo?<\/p>\n<p>\u201cNo est\u00e1bamos en el estado de \u00e1nimo adecuado despu\u00e9s de lo que sucedi\u00f3. Cuando sabes que alguien est\u00e1 haciendo trampa, en un gran partido como ese, tu est\u00f3mago cae. As\u00ed que <b>no est\u00e1bamos muy en sinton\u00eda con nuestra defensa despu\u00e9s de eso<\/b>\u201d, argument\u00f3. Y ampli\u00f3, para ningunear a La Mona Lisa del f\u00fatbol: \u201cTengo que decir que,<b> antes de que la pelota llegara a Maradona, Glenn Hoddle recibi\u00f3 una falta<\/b>. Pero no puedes quitarle nada. Maradona hizo lo que era capaz de hacer\u201d.<\/p>\n<p>\u201cEl equipo entero de Inglaterra sufri\u00f3 porque \u00e9l hizo trampa. Hoy en d\u00eda la gente se queja del VAR, pero hubiese sido brillante para nosotros en esa instancia. (Maradona) <b>Lo admiti\u00f3 de forma indirecta, diciendo que era la <\/b><i><b>Mano de Dios<\/b><\/i><b>. Pero no se disculp\u00f3 ni mostr\u00f3 ning\u00fan remordimiento\u00bb<\/b>, martill\u00f3. <\/p>\n<p>Ese pretexto fue bandera para hablar sobre el tema en cada incursi\u00f3n medi\u00e1tica. Incluso, cuando hizo su partido despedida, resalt\u00f3 que no invit\u00f3 a <i>Pelusa <\/i>porque no se hab\u00eda disculpado. Esa secuencia gener\u00f3 una de las m\u00e1s hilarantes r\u00e9plicas del fantasista.<\/p>\n<p>\u201cEl f\u00fatbol se juega con los pies, se piensa con la cabeza y&#8230; Se hacen goles con la mano tambi\u00e9n. Fijate que hay muy pocos goles con la mano de europeos, porque no tuvieron potrero. La picard\u00eda. Y no era falta de respeto para nadie. Shilton dijo \u2018no lo invito a mi partido homenaje porque me hizo un gol con la mano\u2019.<b> \u00bfY qui\u00e9n quer\u00eda ir a tu partido? Aparte, un arquero&#8230; \u00a1Mir\u00e1 si me va a invitar un arquero!<\/b>\u201c, volvi\u00f3 a dejarlo tirado, manoteando el aire.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/07\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion-2.jpg\" alt=\"Maradona cierra el Gol del Siglo ante la desesperaci\u00f3n de Shilton (Ted Blackbrow\/Daily Mail\/Shutterstock)\" height=\"1742\" width=\"1920\"\/><\/p>\n<p>Su obsesi\u00f3n lo llev\u00f3 a que uno de sus propios compa\u00f1eros, <b>Paul Gascoigne<\/b>, se burlara de \u00e9l. El ex guardameta fue muy criticado cuando, en noviembre de 2020, public\u00f3 un mensaje cr\u00edtico tras la muerte del ex Argentinos, Napoli, Boca, Sevilla, Barcelona y Newell\u2019s. <b>\u201cDiego Maradona tuvo grandeza, pero no deportividad\u201d<\/b>, escribi\u00f3, para luego vender una entrevista televisiva que iba a realizar al d\u00eda siguiente. Su actitud le vali\u00f3 una catarata de reproches. <\/p>\n<p>Pues bien, Gazza no lo perdon\u00f3 frente a las c\u00e1maras. El ex mediocampista ofensivo solt\u00f3 entre risas: \u201c\u00c9l era un \u00edcono, <b>muchos hablan a\u00fan de \u2018La Mano de Dios\u2019, pero eso te hizo quien sos<\/b>\u201d. Shilts se defendi\u00f3: \u201cGracias por eso, pero despu\u00e9s de eso segu\u00ed jugando durante 20 a\u00f1os m\u00e1s\u201d.<\/p>\n<p>En los \u00faltimos d\u00edas, <i>Shilts<\/i> sorprendi\u00f3 con una declaraci\u00f3n que busc\u00f3 bajarle el volumen a una pol\u00e9mica que no envejeci\u00f3, como los m\u00edticos goles de Maradona. \u201cNo voy a mencionar nombres, pero <b>he dejado atr\u00e1s la disputa porque ya han pasado 40 a\u00f1os. He guardado un poco de resentimiento durante muchos tiempo. He estado en Buenos Aires en los \u00faltimos a\u00f1os y la gente de all\u00ed fue fant\u00e1stica conmigo. Fueron brillantes conmigo<\/b>. Por dentro pens\u00e9 que era momento de dejar atr\u00e1s la disputa&#8230; obviamente Maradona ya no est\u00e1 con nosotros\u201d, destac\u00f3 en una entrevista con<i> The Telegraph<\/i> que ofreci\u00f3 antes del partido de los <i>Tres Leones<\/i> ante <b>M\u00e9xico<\/b>.<\/p>\n<p>Habr\u00e1 que esperar para ver si las alternativas del partido no le hacen brotar los viejos resquemores.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Peter Shilton puede colgarse varias medallas por su carrera e incluso en relaci\u00f3n a su vida personal. Desde sus sobrios 183 cent\u00edmetros y la seguridad de sus guantes, edific\u00f3 una trayectoria que lo llev\u00f3, por ejemplo, a disputar tres Mundiales (1982, 1986 y 1990). O a convertirse en el arquero ingl\u00e9s que disput\u00f3 mayor cantidad&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[30],"tags":[39],"class_list":["post-82461","post","type-post","status-publish","format-standard","hentry","category-argentina","tag-deportes"],"magazineBlocksPostFeaturedMedia":{"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"newsmatic-featured":false,"newsmatic-list":false,"newsmatic-thumb":false,"newsmatic-small":false,"newsmatic-grid":false},"magazineBlocksPostAuthor":{"name":"admin","avatar":"https:\/\/secure.gravatar.com\/avatar\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":"0","magazineBlocksPostExcerpt":"Peter Shilton puede colgarse varias medallas por su carrera e incluso en relaci\u00f3n a su vida personal. Desde sus sobrios 183 cent\u00edmetros y la seguridad de sus guantes, edific\u00f3 una trayectoria que lo llev\u00f3, por ejemplo, a disputar tres Mundiales (1982, 1986 y 1990). O a convertirse en el arquero ingl\u00e9s que disput\u00f3 mayor cantidad...","magazineBlocksPostCategories":["Argentina"],"magazineBlocksPostViewCount":10,"magazineBlocksPostReadTime":7,"magazine_blocks_featured_image_url":{"full":false,"medium":false,"thumbnail":false},"magazine_blocks_author":{"display_name":"admin","author_link":"https:\/\/lobosnews.com.ar\/index.php\/author\/lobos-news\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-30\">Argentina<\/a>","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sufri\u00f3 como nadie a Maradona en M\u00e9xico 86, se convirti\u00f3 en \u201cvillano\u201d de Argentina y sorprendi\u00f3 con un pedido de reconciliaci\u00f3n - Lobos News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lobosnews.com.ar\/index.php\/2026\/07\/15\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sufri\u00f3 como nadie a Maradona en M\u00e9xico 86, se convirti\u00f3 en \u201cvillano\u201d de Argentina y sorprendi\u00f3 con un pedido de reconciliaci\u00f3n - Lobos News\" \/>\n<meta property=\"og:description\" content=\"Peter Shilton puede colgarse varias medallas por su carrera e incluso en relaci\u00f3n a su vida personal. Desde sus sobrios 183 cent\u00edmetros y la seguridad de sus guantes, edific\u00f3 una trayectoria que lo llev\u00f3, por ejemplo, a disputar tres Mundiales (1982, 1986 y 1990). O a convertirse en el arquero ingl\u00e9s que disput\u00f3 mayor cantidad...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lobosnews.com.ar\/index.php\/2026\/07\/15\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Lobos News\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T05:22:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T05:33:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/07\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion.jpg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/index.php\\\/2026\\\/07\\\/15\\\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/index.php\\\/2026\\\/07\\\/15\\\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/#\\\/schema\\\/person\\\/232422a593d5c541dd9aef6aaed10943\"},\"headline\":\"Sufri\u00f3 como nadie a Maradona en M\u00e9xico 86, se convirti\u00f3 en \u201cvillano\u201d de Argentina y sorprendi\u00f3 con un pedido de reconciliaci\u00f3n\",\"datePublished\":\"2026-07-15T05:22:23+00:00\",\"dateModified\":\"2026-07-15T05:33:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/index.php\\\/2026\\\/07\\\/15\\\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion\\\/\"},\"wordCount\":1282,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/index.php\\\/2026\\\/07\\\/15\\\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lobosnews.com.ar\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion.jpg\",\"keywords\":[\"Deportes\"],\"articleSection\":[\"Argentina\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lobosnews.com.ar\\\/index.php\\\/2026\\\/07\\\/15\\\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/index.php\\\/2026\\\/07\\\/15\\\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion\\\/\",\"url\":\"https:\\\/\\\/lobosnews.com.ar\\\/index.php\\\/2026\\\/07\\\/15\\\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion\\\/\",\"name\":\"Sufri\u00f3 como nadie a Maradona en M\u00e9xico 86, se convirti\u00f3 en \u201cvillano\u201d de Argentina y sorprendi\u00f3 con un pedido de reconciliaci\u00f3n - Lobos News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/index.php\\\/2026\\\/07\\\/15\\\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/index.php\\\/2026\\\/07\\\/15\\\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lobosnews.com.ar\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion.jpg\",\"datePublished\":\"2026-07-15T05:22:23+00:00\",\"dateModified\":\"2026-07-15T05:33:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/index.php\\\/2026\\\/07\\\/15\\\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lobosnews.com.ar\\\/index.php\\\/2026\\\/07\\\/15\\\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/index.php\\\/2026\\\/07\\\/15\\\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lobosnews.com.ar\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion.jpg\",\"contentUrl\":\"https:\\\/\\\/lobosnews.com.ar\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion.jpg\",\"width\":1920,\"height\":1264},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/index.php\\\/2026\\\/07\\\/15\\\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/lobosnews.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sufri\u00f3 como nadie a Maradona en M\u00e9xico 86, se convirti\u00f3 en \u201cvillano\u201d de Argentina y sorprendi\u00f3 con un pedido de reconciliaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/lobosnews.com.ar\\\/\",\"name\":\"Lobos News\",\"description\":\"Informaci\u00f3n a cada instante\",\"publisher\":{\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lobosnews.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/#organization\",\"name\":\"Lobos News\",\"url\":\"https:\\\/\\\/lobosnews.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lobosnews.com.ar\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logo-lobosnews.png\",\"contentUrl\":\"https:\\\/\\\/lobosnews.com.ar\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logo-lobosnews.png\",\"width\":500,\"height\":200,\"caption\":\"Lobos News\"},\"image\":{\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/#\\\/schema\\\/person\\\/232422a593d5c541dd9aef6aaed10943\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/lobosnews.com.ar\"],\"url\":\"https:\\\/\\\/lobosnews.com.ar\\\/index.php\\\/author\\\/lobos-news\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sufri\u00f3 como nadie a Maradona en M\u00e9xico 86, se convirti\u00f3 en \u201cvillano\u201d de Argentina y sorprendi\u00f3 con un pedido de reconciliaci\u00f3n - Lobos News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lobosnews.com.ar\/index.php\/2026\/07\/15\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion\/","og_locale":"es_ES","og_type":"article","og_title":"Sufri\u00f3 como nadie a Maradona en M\u00e9xico 86, se convirti\u00f3 en \u201cvillano\u201d de Argentina y sorprendi\u00f3 con un pedido de reconciliaci\u00f3n - Lobos News","og_description":"Peter Shilton puede colgarse varias medallas por su carrera e incluso en relaci\u00f3n a su vida personal. Desde sus sobrios 183 cent\u00edmetros y la seguridad de sus guantes, edific\u00f3 una trayectoria que lo llev\u00f3, por ejemplo, a disputar tres Mundiales (1982, 1986 y 1990). O a convertirse en el arquero ingl\u00e9s que disput\u00f3 mayor cantidad...","og_url":"https:\/\/lobosnews.com.ar\/index.php\/2026\/07\/15\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion\/","og_site_name":"Lobos News","article_published_time":"2026-07-15T05:22:23+00:00","article_modified_time":"2026-07-15T05:33:17+00:00","og_image":[{"url":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/07\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion.jpg","type":"","width":"","height":""}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/07\/15\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion\/#article","isPartOf":{"@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/07\/15\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion\/"},"author":{"name":"admin","@id":"https:\/\/lobosnews.com.ar\/#\/schema\/person\/232422a593d5c541dd9aef6aaed10943"},"headline":"Sufri\u00f3 como nadie a Maradona en M\u00e9xico 86, se convirti\u00f3 en \u201cvillano\u201d de Argentina y sorprendi\u00f3 con un pedido de reconciliaci\u00f3n","datePublished":"2026-07-15T05:22:23+00:00","dateModified":"2026-07-15T05:33:17+00:00","mainEntityOfPage":{"@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/07\/15\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion\/"},"wordCount":1282,"commentCount":0,"publisher":{"@id":"https:\/\/lobosnews.com.ar\/#organization"},"image":{"@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/07\/15\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion\/#primaryimage"},"thumbnailUrl":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/07\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion.jpg","keywords":["Deportes"],"articleSection":["Argentina"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lobosnews.com.ar\/index.php\/2026\/07\/15\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/07\/15\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion\/","url":"https:\/\/lobosnews.com.ar\/index.php\/2026\/07\/15\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion\/","name":"Sufri\u00f3 como nadie a Maradona en M\u00e9xico 86, se convirti\u00f3 en \u201cvillano\u201d de Argentina y sorprendi\u00f3 con un pedido de reconciliaci\u00f3n - Lobos News","isPartOf":{"@id":"https:\/\/lobosnews.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/07\/15\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion\/#primaryimage"},"image":{"@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/07\/15\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion\/#primaryimage"},"thumbnailUrl":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/07\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion.jpg","datePublished":"2026-07-15T05:22:23+00:00","dateModified":"2026-07-15T05:33:17+00:00","breadcrumb":{"@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/07\/15\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lobosnews.com.ar\/index.php\/2026\/07\/15\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/07\/15\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion\/#primaryimage","url":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/07\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion.jpg","contentUrl":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/07\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion.jpg","width":1920,"height":1264},{"@type":"BreadcrumbList","@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/07\/15\/sufrio-como-nadie-a-maradona-en-mexico-86-se-convirtio-en-villano-de-argentina-y-sorprendio-con-un-pedido-de-reconciliacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lobosnews.com.ar\/"},{"@type":"ListItem","position":2,"name":"Sufri\u00f3 como nadie a Maradona en M\u00e9xico 86, se convirti\u00f3 en \u201cvillano\u201d de Argentina y sorprendi\u00f3 con un pedido de reconciliaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/lobosnews.com.ar\/#website","url":"https:\/\/lobosnews.com.ar\/","name":"Lobos News","description":"Informaci\u00f3n a cada instante","publisher":{"@id":"https:\/\/lobosnews.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lobosnews.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/lobosnews.com.ar\/#organization","name":"Lobos News","url":"https:\/\/lobosnews.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lobosnews.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/01\/logo-lobosnews.png","contentUrl":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/01\/logo-lobosnews.png","width":500,"height":200,"caption":"Lobos News"},"image":{"@id":"https:\/\/lobosnews.com.ar\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/lobosnews.com.ar\/#\/schema\/person\/232422a593d5c541dd9aef6aaed10943","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/lobosnews.com.ar"],"url":"https:\/\/lobosnews.com.ar\/index.php\/author\/lobos-news\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/82461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=82461"}],"version-history":[{"count":1,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/82461\/revisions"}],"predecessor-version":[{"id":82465,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/82461\/revisions\/82465"}],"wp:attachment":[{"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=82461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=82461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=82461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}