{"id":53685,"date":"2026-05-13T17:04:50","date_gmt":"2026-05-13T17:04:50","guid":{"rendered":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz\/"},"modified":"2026-05-13T19:06:20","modified_gmt":"2026-05-13T19:06:20","slug":"los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz","status":"publish","type":"post","link":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz\/","title":{"rendered":"Los nuevos audios que reprodujeron en el juicio por la muerte de Maradona y comprometieron a Luque, Cosachov y D\u00edaz"},"content":{"rendered":"<p>La \u00faltima audiencia del<span class=\"waslinkname\"> juicio por la muerte de Maradona<\/span> gir\u00f3 en torno a la salud card\u00edaca del Diez. En este contexto, testific\u00f3 un <b>cardi\u00f3logo que lo atendi\u00f3 a Diego<\/b> en septiembre de 2020 en La Plata, quien le hizo unos chequeos de rutina y dijo que<b> intent\u00f3 realizarle un estudio m\u00e1s completo<\/b> para descartar enfermerdades coronarias, pero <b>el imputado Leopoldo Luque se neg\u00f3. <\/b>Dos meses despu\u00e9s, el ex DT falleci\u00f3 de una falla en su coraz\u00f3n.<\/p>\n<p>Tras la declaraci\u00f3n del profesional, los fiscales Patricio Ferrari y Cosme Iribarren reprodujeron ante los jueces un audio que le envi\u00f3 el neurocirujano al testigo en ese entonces, donde se lo escucha <b>decirle que no le hiciera el examen de \u201cperfusi\u00f3n\u201d. <\/b><\/p>\n<p>Este an\u00e1lisis, conocido como <b>\u201ctest de perfusi\u00f3n mioc\u00e1rdica\u201d<\/b> es un estudio no invasivo que eval\u00faa el \u201cflujo sangu\u00edneo al m\u00fasculo card\u00edaco en reposo y bajo esfuerzo\u201d. Para hacerlo, el paciente debe realizar un ejercicio f\u00edsico para ver c\u00f3mo reacciona el coraz\u00f3n. <\/p>\n<p>Si no puede hacer actividad por alguna limitaci\u00f3n, existe la opci\u00f3n de suministrarle unos medicamentos que aceleran el \u00f3rgano simulando que el esfuerzo. <b>No es peligroso, sino de rutina<\/b> y sirve para detectar \u00e1reas con riego sangu\u00edneo insuficiente, isquemia o cicatrices de infartos, seg\u00fan explic\u00f3 el profesional que testific\u00f3.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz.jpg\" alt=\"La diferencia ilustrativa entre un coraz\u00f3n normal y el de Maradona\" height=\"670\" width=\"1170\"\/><\/p>\n<p>En el audio que compromete a Luque, se escucha al neurocirujano decirle al cardi\u00f3logo que atendi\u00f3 al Diez en el sanatorio Ipensa: \u201cHola, Franco, \u00bfc\u00f3mo est\u00e1s? Te mando un audio. A \u00e9l, la vez pasada, le hicieron un eco Doppler, un Doppler, un ecocardio, y tambi\u00e9n de vasos del cuello, electrocardiograma, y los cardi\u00f3logos de la cl\u00ednica Olivos <b>dijeron que estaba todo ok<\/b>. \u00c9l se medica con losart\u00e1n para la presi\u00f3n, pero b\u00e1sicamente eso ser\u00edaSe cort\u00f3 el mensaje. As\u00ed que, b\u00e1sicamente, ser\u00eda eso en principio.<b> Un electrocardiograma, nada de estudios de perfusi\u00f3n, y esas cosas me parecen demasiado\u00bb. <\/b><\/p>\n<p>Y sigue: \u201c<b>La idea es hacerle algo, digamos, general y medio r\u00e1pido,<\/b> por el tema del coronavirus, \u00bfviste? No tenerlo mucho ah\u00ed, y, adem\u00e1s, a \u00e9l no no le simpatiza mucho estar en los sanatorios, estar rodeado de m\u00e9dicos, no le gusta, generalmente. As\u00ed que, bueno, si te parece o suger\u00eds algo m\u00e1s, obviamente te escucho y llegamos a un acuerdo, \u00bfdale? Gracias\u00bb.<\/p>\n<p>Para la fiscal\u00eda, este audio es fundamental para demostrar<b> la falta de atenci\u00f3n a la salud card\u00edaca de Maradona <\/b>a pesar de ser un paciente con antecedentes de p\u00fablico conocimiento. <\/p>\n<p>La defensa de <b>Leopoldo Luque, sin embargo, se enfoca en subrayar que Diego no ten\u00eda advertencias de riesgos card\u00edacos <\/b>al momento de su muerte. En este contexto es que los fiscales decidieron exponer ante los jueces del TOC N\u00b07 de San Isidro<b> dos audios de los otros imputados de la causa, Agustina Cosachov y Carlos D\u00edaz, <\/b>donde se los escucha admitir que Maradona ten\u00eda problemas de coraz\u00f3n y que ellos lo sab\u00edan.<\/p>\n<p>En el primero se la escucha a la <b>psiquiatra Cosachov en di\u00e1logo con D\u00edaz <\/b>hablar de la mediaci\u00f3n para el ex DT <b>contemplando su salud cardiol\u00f3gica.<\/b><\/p>\n<p>\u201cNo, no, no, no. Me parece que no nos metamos con eso, porque, mir\u00e1, el neur\u00f3logo fue y no le dio indicaci\u00f3n de eso. Yo, por el momento, tratar\u00eda de optimizar un poco lo que tiene. D\u00e9jame que yo lo hable con Marcela, porque capaz podemos bajarle la quetiapina de la ma\u00f1ana y agregarle un estabilizador que sea un poco m\u00e1s power\u201d, se escucha al principio.<\/p>\n<p>El audio contin\u00faa: \u201cNo, modafinilo no me cierra primero <b>por la cuesti\u00f3n card\u00edaca de los antecedentes de \u00e9l<\/b>, y no me cierra porque podr\u00eda incrementarle el temblor por al ser un estimulante. Lo he usado, pero con otro tipo de pacientes. En este caso, mucho no me mucho no me cierra. Pero dejame que lo hable con con Marcela. Lo de la levodopa no, no me parece necesario tampoco\u00bb.<\/p>\n<p>El mensaje de voz expuesto de <b>Carlos D\u00edaz, el psic\u00f3logo<\/b>, es post muerte de Diego, donde tambi\u00e9n se lo escucha hablar de la salud del coraz\u00f3n del paciente.<\/p>\n<p>\u201cEsc\u00fachame, te digo lo que es b\u00e1sico. Diego Maradona se muri\u00f3 por una cuesti\u00f3n card\u00edaca de hace 20 a\u00f1os, \u00bfs\u00ed? O sea, si ellos dec\u00edan que no estaba para irse, lo hicieron para resguardarse, obvio, \u00bfok? Ustedes firmaron junto a las hijas, y no es que \u00e9l se muri\u00f3 por una cuesti\u00f3n de la cabeza, \u00bfentend\u00e9s? Y que fue imprudente externarlo por eso.<b> Lo del coraz\u00f3n no tuvo nada que ver con lo de la cabeza, eso nos dijo Luque, <\/b>y entiendo que es as\u00ed. Por lo tanto, no tiene nada que ver una cosa con la otra. No s\u00e9 si soy claro lo que planteo\u00bb, dice D\u00edaz.<\/p>\n<p>Y concluye: \u201cTal vez la justicia hace alguna boludez, \u00bfviste? Para, pero no no no hay ac\u00e1 una responsabilidad.No es que le diste un medicamento que lo pudo haber matado, \u00bfviste? Que hubo una sobredosis de rivotril, yo qu\u00e9 s\u00e9, \u00bfviste? O sea, no, olvidate, olvidate. O sea, como yo te dije, esto mismo hace un mes, era un quilombo mundial, mundial. Pero hoy todo bien, todo en regla. Olvidate\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La \u00faltima audiencia del juicio por la muerte de Maradona gir\u00f3 en torno a la salud card\u00edaca del Diez. En este contexto, testific\u00f3 un cardi\u00f3logo que lo atendi\u00f3 a Diego en septiembre de 2020 en La Plata, quien le hizo unos chequeos de rutina y dijo que intent\u00f3 realizarle un estudio m\u00e1s completo para descartar&#8230;<\/p>\n","protected":false},"author":1,"featured_media":53688,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[31,30,32,77,84,35,36,37],"tags":[],"class_list":["post-53685","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-argentina","category-economia","category-inseguridad","category-masradios-com","category-nacionales","category-seguridad","category-sociedad"],"magazineBlocksPostFeaturedMedia":{"thumbnail":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz-150x150.jpg","medium":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz-300x172.jpg","medium_large":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz-768x440.jpg","large":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz-1024x586.jpg","1536x1536":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz.jpg","2048x2048":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz.jpg","newsmatic-featured":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz-820x545.jpg","newsmatic-list":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz-600x400.jpg","newsmatic-thumb":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz-300x200.jpg","newsmatic-small":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz-150x95.jpg","newsmatic-grid":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz-400x250.jpg"},"magazineBlocksPostAuthor":{"name":"admin","avatar":"https:\/\/secure.gravatar.com\/avatar\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":"0","magazineBlocksPostExcerpt":"La \u00faltima audiencia del juicio por la muerte de Maradona gir\u00f3 en torno a la salud card\u00edaca del Diez. En este contexto, testific\u00f3 un cardi\u00f3logo que lo atendi\u00f3 a Diego en septiembre de 2020 en La Plata, quien le hizo unos chequeos de rutina y dijo que intent\u00f3 realizarle un estudio m\u00e1s completo para descartar...","magazineBlocksPostCategories":["Actualidad","Argentina","econom\u00eda","inseguridad","masradios.com","nacionales","seguridad","sociedad"],"magazineBlocksPostViewCount":4,"magazineBlocksPostReadTime":5,"magazine_blocks_featured_image_url":{"full":["https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz.jpg",1170,670,false],"medium":["https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz-300x172.jpg",300,172,true],"thumbnail":["https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz-150x150.jpg",150,150,true]},"magazine_blocks_author":{"display_name":"admin","author_link":"https:\/\/lobosnews.com.ar\/index.php\/author\/lobos-news\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-31\">Actualidad<\/a> <a href=\"#\" class=\"category-link category-link-30\">Argentina<\/a> <a href=\"#\" class=\"category-link category-link-32\">econom\u00eda<\/a> <a href=\"#\" class=\"category-link category-link-77\">inseguridad<\/a> <a href=\"#\" class=\"category-link category-link-84\">masradios.com<\/a> <a href=\"#\" class=\"category-link category-link-35\">nacionales<\/a> <a href=\"#\" class=\"category-link category-link-36\">seguridad<\/a> <a href=\"#\" class=\"category-link category-link-37\">sociedad<\/a>","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Los nuevos audios que reprodujeron en el juicio por la muerte de Maradona y comprometieron a Luque, Cosachov y D\u00edaz - Lobos News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los nuevos audios que reprodujeron en el juicio por la muerte de Maradona y comprometieron a Luque, Cosachov y D\u00edaz - Lobos News\" \/>\n<meta property=\"og:description\" content=\"La \u00faltima audiencia del juicio por la muerte de Maradona gir\u00f3 en torno a la salud card\u00edaca del Diez. En este contexto, testific\u00f3 un cardi\u00f3logo que lo atendi\u00f3 a Diego en septiembre de 2020 en La Plata, quien le hizo unos chequeos de rutina y dijo que intent\u00f3 realizarle un estudio m\u00e1s completo para descartar...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz\/\" \/>\n<meta property=\"og:site_name\" content=\"Lobos News\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T17:04:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T19:06:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz.jpg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/lobosnews.com.ar\/#\/schema\/person\/232422a593d5c541dd9aef6aaed10943\"},\"headline\":\"Los nuevos audios que reprodujeron en el juicio por la muerte de Maradona y comprometieron a Luque, Cosachov y D\u00edaz\",\"datePublished\":\"2026-05-13T17:04:50+00:00\",\"dateModified\":\"2026-05-13T19:06:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz\/\"},\"wordCount\":935,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/lobosnews.com.ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz.jpg\",\"articleSection\":[\"Actualidad\",\"Argentina\",\"econom\u00eda\",\"inseguridad\",\"masradios.com\",\"nacionales\",\"seguridad\",\"sociedad\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz\/\",\"url\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz\/\",\"name\":\"Los nuevos audios que reprodujeron en el juicio por la muerte de Maradona y comprometieron a Luque, Cosachov y D\u00edaz - Lobos News\",\"isPartOf\":{\"@id\":\"https:\/\/lobosnews.com.ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz.jpg\",\"datePublished\":\"2026-05-13T17:04:50+00:00\",\"dateModified\":\"2026-05-13T19:06:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz\/#primaryimage\",\"url\":\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz.jpg\",\"contentUrl\":\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz.jpg\",\"width\":1170,\"height\":670,\"caption\":\"Los nuevos audios que reprodujeron en el juicio por la muerte de Maradona y comprometieron a Luque, Cosachov y D\u00edaz\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/lobosnews.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los nuevos audios que reprodujeron en el juicio por la muerte de Maradona y comprometieron a Luque, Cosachov y D\u00edaz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lobosnews.com.ar\/#website\",\"url\":\"https:\/\/lobosnews.com.ar\/\",\"name\":\"Lobos News\",\"description\":\"Informaci\u00f3n a cada instante\",\"publisher\":{\"@id\":\"https:\/\/lobosnews.com.ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lobosnews.com.ar\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/lobosnews.com.ar\/#organization\",\"name\":\"Lobos News\",\"url\":\"https:\/\/lobosnews.com.ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/lobosnews.com.ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/01\/logo-lobosnews.png\",\"contentUrl\":\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/01\/logo-lobosnews.png\",\"width\":500,\"height\":200,\"caption\":\"Lobos News\"},\"image\":{\"@id\":\"https:\/\/lobosnews.com.ar\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/lobosnews.com.ar\/#\/schema\/person\/232422a593d5c541dd9aef6aaed10943\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/lobosnews.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/lobosnews.com.ar\"],\"url\":\"https:\/\/lobosnews.com.ar\/index.php\/author\/lobos-news\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los nuevos audios que reprodujeron en el juicio por la muerte de Maradona y comprometieron a Luque, Cosachov y D\u00edaz - Lobos News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz\/","og_locale":"es_ES","og_type":"article","og_title":"Los nuevos audios que reprodujeron en el juicio por la muerte de Maradona y comprometieron a Luque, Cosachov y D\u00edaz - Lobos News","og_description":"La \u00faltima audiencia del juicio por la muerte de Maradona gir\u00f3 en torno a la salud card\u00edaca del Diez. En este contexto, testific\u00f3 un cardi\u00f3logo que lo atendi\u00f3 a Diego en septiembre de 2020 en La Plata, quien le hizo unos chequeos de rutina y dijo que intent\u00f3 realizarle un estudio m\u00e1s completo para descartar...","og_url":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz\/","og_site_name":"Lobos News","article_published_time":"2026-05-13T17:04:50+00:00","article_modified_time":"2026-05-13T19:06:20+00:00","og_image":[{"url":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz.jpg","type":"","width":"","height":""}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz\/#article","isPartOf":{"@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz\/"},"author":{"name":"admin","@id":"https:\/\/lobosnews.com.ar\/#\/schema\/person\/232422a593d5c541dd9aef6aaed10943"},"headline":"Los nuevos audios que reprodujeron en el juicio por la muerte de Maradona y comprometieron a Luque, Cosachov y D\u00edaz","datePublished":"2026-05-13T17:04:50+00:00","dateModified":"2026-05-13T19:06:20+00:00","mainEntityOfPage":{"@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz\/"},"wordCount":935,"commentCount":0,"publisher":{"@id":"https:\/\/lobosnews.com.ar\/#organization"},"image":{"@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz\/#primaryimage"},"thumbnailUrl":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz.jpg","articleSection":["Actualidad","Argentina","econom\u00eda","inseguridad","masradios.com","nacionales","seguridad","sociedad"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz\/","url":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz\/","name":"Los nuevos audios que reprodujeron en el juicio por la muerte de Maradona y comprometieron a Luque, Cosachov y D\u00edaz - Lobos News","isPartOf":{"@id":"https:\/\/lobosnews.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz\/#primaryimage"},"image":{"@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz\/#primaryimage"},"thumbnailUrl":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz.jpg","datePublished":"2026-05-13T17:04:50+00:00","dateModified":"2026-05-13T19:06:20+00:00","breadcrumb":{"@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz\/#primaryimage","url":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz.jpg","contentUrl":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz.jpg","width":1170,"height":670,"caption":"Los nuevos audios que reprodujeron en el juicio por la muerte de Maradona y comprometieron a Luque, Cosachov y D\u00edaz"},{"@type":"BreadcrumbList","@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lobosnews.com.ar\/"},{"@type":"ListItem","position":2,"name":"Los nuevos audios que reprodujeron en el juicio por la muerte de Maradona y comprometieron a Luque, Cosachov y D\u00edaz"}]},{"@type":"WebSite","@id":"https:\/\/lobosnews.com.ar\/#website","url":"https:\/\/lobosnews.com.ar\/","name":"Lobos News","description":"Informaci\u00f3n a cada instante","publisher":{"@id":"https:\/\/lobosnews.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lobosnews.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/lobosnews.com.ar\/#organization","name":"Lobos News","url":"https:\/\/lobosnews.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lobosnews.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/01\/logo-lobosnews.png","contentUrl":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/01\/logo-lobosnews.png","width":500,"height":200,"caption":"Lobos News"},"image":{"@id":"https:\/\/lobosnews.com.ar\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/lobosnews.com.ar\/#\/schema\/person\/232422a593d5c541dd9aef6aaed10943","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lobosnews.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/lobosnews.com.ar"],"url":"https:\/\/lobosnews.com.ar\/index.php\/author\/lobos-news\/"}]}},"jetpack_featured_media_url":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/los-nuevos-audios-que-reprodujeron-en-el-juicio-por-la-muerte-de-maradona-y-comprometieron-a-luque-cosachov-y-diaz.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/53685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=53685"}],"version-history":[{"count":1,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/53685\/revisions"}],"predecessor-version":[{"id":53687,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/53685\/revisions\/53687"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/media\/53688"}],"wp:attachment":[{"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=53685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=53685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=53685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}