{"id":53354,"date":"2026-05-13T05:58:58","date_gmt":"2026-05-13T05:58:58","guid":{"rendered":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia\/"},"modified":"2026-05-13T12:19:00","modified_gmt":"2026-05-13T12:19:00","slug":"por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia","status":"publish","type":"post","link":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia\/","title":{"rendered":"Por qu\u00e9 el Rally Dakar adelant\u00f3 su recorrido en Arabia Saudita 2027 pese a la crisis en Medio Oriente: el plan de emergencia"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia.jpg\" alt=\"Se adelant\u00f3 el recorrido del Rally Dakar 2027, pero puede haber un cambio de \u00faltimo minuto (REUTERS\/Stephane Mahe)\" height=\"2896\" width=\"4294\"\/><\/p>\n<p>El <span class=\"waslinkname\"><b>Rally Dakar<\/b> anunci\u00f3 el recorrido de su octava presencia en <b>Arabia Saudita<\/b><\/span> del 1 al 15 de enero de 2027, pese al marco de conflicto en Medio Oriente. Tanto el Gobierno local como <b>Amaury Sport Organisation (ASO)<\/b>, la empresa a cargo del evento, apostaron fuerte de cara a la 49\u00aa edici\u00f3n. Habitualmente, los detalles de la extensi\u00f3n de la carrera m\u00e1s dura del mundo se informaban en noviembre, pero ahora se adelant\u00f3 y hay un motivo. Tampoco se dej\u00f3 nada librado al azar e <b>Infobae <\/b>fue a fondo y pudo saber qu\u00e9 puede llegar a pasar en el peor escenario. <\/p>\n<p>Para el a\u00f1o pr\u00f3ximo, se inform\u00f3 una ruta total de <b>8.390 kil\u00f3metros y 5.320 cronometrados<\/b>, es decir, de pura carrera. Ser\u00e1n <b>13 etapas<\/b>, <b>nueve campamentos<\/b> y el epicentro ser\u00e1 en Yeda, en las instalaciones del <i>Estadio Rey Abdullah<\/i>. La mayor parte de la competencia atravesar\u00e1 el sur del reino saudita, que al haber adelantado la fecha de lanzamiento de su recorrido cumpli\u00f3 con su objetivo de ratificarse como sede de la competencia. <\/p>\n<p>La regi\u00f3n sigue bajo un clima de tensi\u00f3n, pero los saud\u00edes sienten que si no avanzan en la confirmaci\u00f3n de sus eventos est\u00e1n dando el brazo a torcer ante Ir\u00e1n. Los bombardeos obligaron a cancelar los Grandes Premios de F1 de <b>Bahr\u00e9in<\/b> y <b>Arabia Saudita<\/b>, programados para el 12 y 19 de abril, respectivamente. Lo mismo sucedi\u00f3 con el <b>Campeonato Mundial de Endurance (WEC)<\/b>,<b> <\/b>que posterg\u00f3 su apertura de la temporada que estaba programado para el 28 de marzo en Qatar y se pas\u00f3 para el 19 de abril en Imola. <\/p>\n<p>En este contexto, ASO, por intermedio de <b>David Castera<\/b>, el Director del<b> Rally Dakar<\/b>, se reuni\u00f3 con emisarios sauditas que le garantizaron que, con este panorama y de no escalar el conflicto, iban a estar dadas las condiciones para hacer la carrera. Para eso se adelant\u00f3 la planificaci\u00f3n del recorrido que consiste primero en verlo de forma virtual desde un mapa satelital, luego armarlo de manera digital y la \u00faltima instancia es recorrerlo de forma presencial para chequear que est\u00e9n dadas las condiciones reales. Habitualmente esta \u00faltima fase tiene un tiempo l\u00edmite de hacerse hasta julio, pero <b>en este caso la organizaci\u00f3n se adelant\u00f3 para poder confirmar el recorrido el pasado 6 de mayo<\/b>. <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia-1.jpg\" alt=\"El Director del Rally Dakar, David Castera, volvi\u00f3 a Arabia Saudita e hizo el recorrido completo de la edici\u00f3n 2027 del Rally Dakar (REUTERS\/Stephane Mahe)\" height=\"3871\" width=\"5834\"\/><\/p>\n<p>El plan de Arabia Saudita para garantizar el Rally Dakar consiste en primero recuperar su GP de F1 y apuestan a hacerlo el 6 de diciembre, corriendo una semana el de <b>Abu Dhabi<\/b>, que suele ser el cierre de temporada. Con la realizaci\u00f3n de la competencia de la M\u00e1xima, se busca ratificar la 49\u00aa edici\u00f3n de la carrera m\u00e1s extrema del planeta en enero. <\/p>\n<p>El <b>Rally Dakar <\/b>es la primera de las cinco fechas del <b>Campeonato Mundial de Rally Raid<\/b>, el cual retorna este a\u00f1o a Argentina con un nuevo cap\u00edtulo del <b>Desaf\u00edo Ruta 40<\/b>, que se llevar\u00e1 a cabo del 24 al 29 de mayo en <b>Mendoza<\/b> y <b>San Juan<\/b>. La cita tiene 151 inscriptos, entre los que se destacan<b> Nasser Al-Attiyah<\/b> (5 veces ganador del Rally Dakar), <b>Carlos Sainz <\/b>(4 triunfos) y <b>S\u00e9bastien Loeb <\/b>(9 t\u00edtulos Mundiales de Rally), adem\u00e1s de los argentinos, como el reciente vencedor en motos, <b>Luciano Benavides<\/b>. La \u00faltima cita del a\u00f1o ser\u00e1 el <b>Rally de Abu Dhabi<\/b>, del 22 al 29 de noviembre. Todos los veh\u00edculos que participen ser\u00e1n trasladados hacia <b>Arabia Saudita <\/b>y tras<b> 1.000 kil\u00f3metros<\/b> llegar\u00e1n para comenzar los preparativos del evento en enero. <\/p>\n<p>Tanto ASO como las autoridades del Gobierno saudita trabajan seg\u00fan lo coordinado, pero saben que puede darse el peor escenario y ser\u00eda que el conflicto b\u00e9lico en la regi\u00f3n escale de tal forma que impida las condiciones necesarias de seguridad para la carrera. En caso de que esto pase, <b>Infobae<\/b> puede confirmar de muy buena fuente <b>que existe un \u201cPlan B\u201d<\/b>. \u00bfEl lugar? Por el momento se guarda bajo cuatro llaves. S\u00ed se puede adelantar que<b> no es Sudam\u00e9rica<\/b>, que fue sede durante una d\u00e9cada entre 2009 y 2019. <\/p>\n<p>Nuestra regi\u00f3n recibi\u00f3 la carrera luego de la cancelaci\u00f3n de 2008 (la \u00fanica hasta ahora) por las amenazas de terroristas de Al-Qaeda, que fueron filtradas por el servicio de inteligencia franc\u00e9s. El calor y la pasi\u00f3n del p\u00fablico que acompa\u00f1\u00f3 los recorridos en <b>Argentina, Chile, Paraguay, Bolivia y Per\u00fa<\/b> no pudo con los <b>75 millones de d\u00f3lares<\/b> que Arabia Saudita habr\u00eda pagado en el contrato inicial de un lustro, unos <b>15 millones anuales<\/b>, que <b>superaron el canon sudamericano. <\/b><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia-2.jpg\" alt=\"El qatar\u00ed Nasser Al-Attiyah y el argentino Luciano Benavides, ganadores en la \u00faltima edici\u00f3n del Rally Dakar en autos y motos. Ambos estar\u00e1n a fin de mes en Mendoza y San Juan para el Desaf\u00edo Ruta 40 (Europa Press)\" height=\"1280\" width=\"1920\"\/><\/p>\n<p><b>Arabia Saudita<\/b> sum\u00f3 al <b>Rally Dakar <\/b>como parte de una pol\u00edtica de Estado para fomentar el turismo. Tiene <b>F1, Rally Mundial, F\u00f3rmula E<\/b>, los eventos de<b> box de primer nivel <\/b>o el <b>Mundial de F\u00fatbol 2034<\/b> son claros ejemplos. <\/p>\n<p>En la \u00faltima edici\u00f3n del <b>Rally Dakar<\/b>, este medio le pregunt\u00f3 a <b>Castera<\/b> a d\u00f3nde le gustar\u00eda ir o volver y el galo respondi\u00f3 sonriente \u201cmuy bueno\u201d. Aunque luego se puso serio y analiz\u00f3 el panorama real: \u201c<b>No es d\u00f3nde quiero ir, es d\u00f3nde podemos ir. Es la verdad. Porque para hacer nuestro deporte se necesita un desierto grande. Aqu\u00ed lo tenemos. No hay muchos lugares en el mundo donde se pueda ir. Entonces vamos a ver todas las posibilidades<\/b>\u201d. <\/p>\n<p>El m\u00e1ximo dirigente del <b>Rally Dakar<\/b> reconoci\u00f3 que hay un equipo de trabajo analizando posibles nuevos destinos: \u201c<b>Hemos empezado justo ahora porque todo se prepara con anticipaci\u00f3n. Entonces estamos trabajando para ver d\u00f3nde va a estar el futuro del Dakar<\/b>. <b>\u00c1frica me parece muy dif\u00edcil porque la parte norte est\u00e1 totalmente imposible de entrar con la geopol\u00edtica actual. Entonces vamos a estudiar eso con tranquilidad<\/b>\u201d. <\/p>\n<p>El <b>Rally Dakar<\/b> se encamina a sus 50 a\u00f1os y fue en diciembre de 1978 cuando larg\u00f3 su primera carrera a metros de la Torre Eiffel y de ah\u00ed su hist\u00f3rico nombre original de <b>Par\u00eds-Dakar<\/b>. El futuro del evento va m\u00e1s all\u00e1 de los petrod\u00f3lares sauditas. En ASO no negocian la seguridad y est\u00e1n preparados para una eventual mudanza. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Rally Dakar anunci\u00f3 el recorrido de su octava presencia en Arabia Saudita del 1 al 15 de enero de 2027, pese al marco de conflicto en Medio Oriente. Tanto el Gobierno local como Amaury Sport Organisation (ASO), la empresa a cargo del evento, apostaron fuerte de cara a la 49\u00aa edici\u00f3n. Habitualmente, los detalles&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[30],"tags":[39],"class_list":["post-53354","post","type-post","status-publish","format-standard","hentry","category-argentina","tag-deportes"],"magazineBlocksPostFeaturedMedia":{"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"newsmatic-featured":false,"newsmatic-list":false,"newsmatic-thumb":false,"newsmatic-small":false,"newsmatic-grid":false},"magazineBlocksPostAuthor":{"name":"admin","avatar":"https:\/\/secure.gravatar.com\/avatar\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":"0","magazineBlocksPostExcerpt":"El Rally Dakar anunci\u00f3 el recorrido de su octava presencia en Arabia Saudita del 1 al 15 de enero de 2027, pese al marco de conflicto en Medio Oriente. Tanto el Gobierno local como Amaury Sport Organisation (ASO), la empresa a cargo del evento, apostaron fuerte de cara a la 49\u00aa edici\u00f3n. Habitualmente, los detalles...","magazineBlocksPostCategories":["Argentina"],"magazineBlocksPostViewCount":15,"magazineBlocksPostReadTime":6,"magazine_blocks_featured_image_url":{"full":false,"medium":false,"thumbnail":false},"magazine_blocks_author":{"display_name":"admin","author_link":"https:\/\/lobosnews.com.ar\/index.php\/author\/lobos-news\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-30\">Argentina<\/a>","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Por qu\u00e9 el Rally Dakar adelant\u00f3 su recorrido en Arabia Saudita 2027 pese a la crisis en Medio Oriente: el plan de emergencia - Lobos News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Por qu\u00e9 el Rally Dakar adelant\u00f3 su recorrido en Arabia Saudita 2027 pese a la crisis en Medio Oriente: el plan de emergencia - Lobos News\" \/>\n<meta property=\"og:description\" content=\"El Rally Dakar anunci\u00f3 el recorrido de su octava presencia en Arabia Saudita del 1 al 15 de enero de 2027, pese al marco de conflicto en Medio Oriente. Tanto el Gobierno local como Amaury Sport Organisation (ASO), la empresa a cargo del evento, apostaron fuerte de cara a la 49\u00aa edici\u00f3n. Habitualmente, los detalles...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia\/\" \/>\n<meta property=\"og:site_name\" content=\"Lobos News\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T05:58:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T12:19:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia.jpg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/lobosnews.com.ar\/#\/schema\/person\/232422a593d5c541dd9aef6aaed10943\"},\"headline\":\"Por qu\u00e9 el Rally Dakar adelant\u00f3 su recorrido en Arabia Saudita 2027 pese a la crisis en Medio Oriente: el plan de emergencia\",\"datePublished\":\"2026-05-13T05:58:58+00:00\",\"dateModified\":\"2026-05-13T12:19:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia\/\"},\"wordCount\":1036,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/lobosnews.com.ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia.jpg\",\"keywords\":[\"Deportes\"],\"articleSection\":[\"Argentina\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia\/\",\"url\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia\/\",\"name\":\"Por qu\u00e9 el Rally Dakar adelant\u00f3 su recorrido en Arabia Saudita 2027 pese a la crisis en Medio Oriente: el plan de emergencia - Lobos News\",\"isPartOf\":{\"@id\":\"https:\/\/lobosnews.com.ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia.jpg\",\"datePublished\":\"2026-05-13T05:58:58+00:00\",\"dateModified\":\"2026-05-13T12:19:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia\/#primaryimage\",\"url\":\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia.jpg\",\"contentUrl\":\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/lobosnews.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Por qu\u00e9 el Rally Dakar adelant\u00f3 su recorrido en Arabia Saudita 2027 pese a la crisis en Medio Oriente: el plan de emergencia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lobosnews.com.ar\/#website\",\"url\":\"https:\/\/lobosnews.com.ar\/\",\"name\":\"Lobos News\",\"description\":\"Informaci\u00f3n a cada instante\",\"publisher\":{\"@id\":\"https:\/\/lobosnews.com.ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lobosnews.com.ar\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/lobosnews.com.ar\/#organization\",\"name\":\"Lobos News\",\"url\":\"https:\/\/lobosnews.com.ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/lobosnews.com.ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/01\/logo-lobosnews.png\",\"contentUrl\":\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/01\/logo-lobosnews.png\",\"width\":500,\"height\":200,\"caption\":\"Lobos News\"},\"image\":{\"@id\":\"https:\/\/lobosnews.com.ar\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/lobosnews.com.ar\/#\/schema\/person\/232422a593d5c541dd9aef6aaed10943\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/lobosnews.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/lobosnews.com.ar\"],\"url\":\"https:\/\/lobosnews.com.ar\/index.php\/author\/lobos-news\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Por qu\u00e9 el Rally Dakar adelant\u00f3 su recorrido en Arabia Saudita 2027 pese a la crisis en Medio Oriente: el plan de emergencia - Lobos News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia\/","og_locale":"es_ES","og_type":"article","og_title":"Por qu\u00e9 el Rally Dakar adelant\u00f3 su recorrido en Arabia Saudita 2027 pese a la crisis en Medio Oriente: el plan de emergencia - Lobos News","og_description":"El Rally Dakar anunci\u00f3 el recorrido de su octava presencia en Arabia Saudita del 1 al 15 de enero de 2027, pese al marco de conflicto en Medio Oriente. Tanto el Gobierno local como Amaury Sport Organisation (ASO), la empresa a cargo del evento, apostaron fuerte de cara a la 49\u00aa edici\u00f3n. Habitualmente, los detalles...","og_url":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia\/","og_site_name":"Lobos News","article_published_time":"2026-05-13T05:58:58+00:00","article_modified_time":"2026-05-13T12:19:00+00:00","og_image":[{"url":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia.jpg","type":"","width":"","height":""}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia\/#article","isPartOf":{"@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia\/"},"author":{"name":"admin","@id":"https:\/\/lobosnews.com.ar\/#\/schema\/person\/232422a593d5c541dd9aef6aaed10943"},"headline":"Por qu\u00e9 el Rally Dakar adelant\u00f3 su recorrido en Arabia Saudita 2027 pese a la crisis en Medio Oriente: el plan de emergencia","datePublished":"2026-05-13T05:58:58+00:00","dateModified":"2026-05-13T12:19:00+00:00","mainEntityOfPage":{"@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia\/"},"wordCount":1036,"commentCount":0,"publisher":{"@id":"https:\/\/lobosnews.com.ar\/#organization"},"image":{"@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia\/#primaryimage"},"thumbnailUrl":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia.jpg","keywords":["Deportes"],"articleSection":["Argentina"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia\/","url":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia\/","name":"Por qu\u00e9 el Rally Dakar adelant\u00f3 su recorrido en Arabia Saudita 2027 pese a la crisis en Medio Oriente: el plan de emergencia - Lobos News","isPartOf":{"@id":"https:\/\/lobosnews.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia\/#primaryimage"},"image":{"@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia\/#primaryimage"},"thumbnailUrl":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia.jpg","datePublished":"2026-05-13T05:58:58+00:00","dateModified":"2026-05-13T12:19:00+00:00","breadcrumb":{"@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia\/#primaryimage","url":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia.jpg","contentUrl":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/por-que-el-rally-dakar-adelanto-su-recorrido-en-arabia-saudita-2027-pese-a-la-crisis-en-medio-oriente-el-plan-de-emergencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lobosnews.com.ar\/"},{"@type":"ListItem","position":2,"name":"Por qu\u00e9 el Rally Dakar adelant\u00f3 su recorrido en Arabia Saudita 2027 pese a la crisis en Medio Oriente: el plan de emergencia"}]},{"@type":"WebSite","@id":"https:\/\/lobosnews.com.ar\/#website","url":"https:\/\/lobosnews.com.ar\/","name":"Lobos News","description":"Informaci\u00f3n a cada instante","publisher":{"@id":"https:\/\/lobosnews.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lobosnews.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/lobosnews.com.ar\/#organization","name":"Lobos News","url":"https:\/\/lobosnews.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lobosnews.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/01\/logo-lobosnews.png","contentUrl":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/01\/logo-lobosnews.png","width":500,"height":200,"caption":"Lobos News"},"image":{"@id":"https:\/\/lobosnews.com.ar\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/lobosnews.com.ar\/#\/schema\/person\/232422a593d5c541dd9aef6aaed10943","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lobosnews.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/lobosnews.com.ar"],"url":"https:\/\/lobosnews.com.ar\/index.php\/author\/lobos-news\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/53354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=53354"}],"version-history":[{"count":1,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/53354\/revisions"}],"predecessor-version":[{"id":53358,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/53354\/revisions\/53358"}],"wp:attachment":[{"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=53354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=53354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=53354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}