{"id":53272,"date":"2026-05-13T05:00:00","date_gmt":"2026-05-13T05:00:00","guid":{"rendered":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-2\/"},"modified":"2026-05-13T06:40:27","modified_gmt":"2026-05-13T06:40:27","slug":"mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-2","status":"publish","type":"post","link":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-2\/","title":{"rendered":"Mariano Mart\u00ednez en \u201cLo de Pampita\u201d: \u201cQuiero cuidar mi relaci\u00f3n de lo medi\u00e1tico\u201d"},"content":{"rendered":"<p><span class=\"waslinkname\"><b>Mariano Mart\u00ednez<\/b><\/span><b> <\/b>\u20145 de diciembre de 1978, Buenos Aires\u2014 se consolid\u00f3 como una de las figuras m\u00e1s reconocibles de la televisi\u00f3n argentina gracias a una trayectoria que abarca m\u00e1s de dos d\u00e9cadas en distintos formatos, desde telenovelas hasta teatro y cine, y por la obtenci\u00f3n de galardones que evidencian su llegada al p\u00fablico m\u00e1s joven. Entre sus logros destaca el <b>Premio Nickelodeon Kids\u2019 Choice Awards Argentina al Actor Favorito en 2015<\/b>, obtenido tras el \u00e9xito de <i><b>Esperanza m\u00eda<\/b><\/i>. Su rol protag\u00f3nico en esa tira, <b>interpretando al sacerdote Tom\u00e1s Ortiz<\/b>, marc\u00f3 un momento central en su carrera.<\/p>\n<p>Sin embargo, la fama lleg\u00f3 a\u00f1os anteriores. Luego de su irrupci\u00f3n juvenil a los diecis\u00e9is a\u00f1os en <i><b>Por siempre mujercitas<\/b><\/i>, Mart\u00ednez consolid\u00f3 su perfil en el g\u00e9nero de las telenovelas al participar en ciclos emblem\u00e1ticos como <i><b>Son amores<\/b><\/i>, transmitida en 2002 y 2003 por Canal 13. <\/p>\n<p>En este proyecto, interpret\u00f3 a <b>Mart\u00edn Marquesi<\/b>, un personaje que combinaba la faceta de cantante y futbolista, que lo catapult\u00f3 a la popularidad. Un dato relevante de su versatilidad art\u00edstica es su experiencia en la m\u00fasica, ya que <b>grab\u00f3 un CD bajo el t\u00edtulo <\/b><i><b>Mart\u00edn \u2018Rey Sol\u2019 Marquesi<\/b><\/i> en el que recre\u00f3 las canciones de dicho personaje. Adem\u00e1s de la reversi\u00f3n que hizo el a\u00f1o pasado con el cantante uruguayo <b>El Reja<\/b>.<\/p>\n<p>En los \u00faltimos a\u00f1os, Mart\u00ednez diversific\u00f3 sus proyectos abordando propuestas teatrales y sumando experiencias en la producci\u00f3n televisiva. De hecho, <b>por estos d\u00edas, triunfa con <\/b><i><b>Ni media palabra<\/b><\/i><b>, la obra que encabeza junto a Nicol\u00e1s Cabr\u00e9 (otra vez la dupla de \u00a1<\/b><i><b>Son amores<\/b><\/i><b>!) y Bicho G\u00f3mez, en la sala Picasso del Paseo La Plaza.<\/b> Tres hombres. Un juego. Una visita tan inesperada como inc\u00f3moda. Lo que parec\u00eda una noche cualquiera se convierte en una sucesi\u00f3n de situaciones imprevisibles, donde nada termina como estaba pensado&#8230; Por ah\u00ed pasa la historia de esta comedia familiar que viene de un gran suceso veraniego en Carlos Paz (gan\u00f3 como <i>Mejor Comedia<\/i> y <i>Mejor Actor<\/i>, Nico Cabr\u00e9). <\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico.jpg\" alt=\"\"Esa gente que nos ve\u00eda con Nico cuando eran j\u00f3venes como nosotros traen a sus hijos y les muestran de qu\u00e9 se re\u00edan. Y la obra trata de eso, de pasar un buen rato, de que sea una fiesta. 'Ni media palabra' est\u00e1 planteada as\u00ed y as\u00ed la recibe la gente\", cuenta, orgulloso, de su \u00e9xito actual junto a Nicol\u00e1s Cabr\u00e9 y Bicho G\u00f3mez en el Paseo La Plaza\" height=\"1278\" width=\"1920\"\/><\/p>\n<p>A su trayectoria actoral se suma una faceta personal marcada por la formaci\u00f3n y la vida familiar en la ciudad de Buenos Aires y el Gran Buenos Aires. <b>Nacido en el barrio de La Boca, Mart\u00ednez creci\u00f3 en Villa Soldati y m\u00e1s tarde en Avellaneda.<\/b> Entre 2012 y 2015, <b>estuvo casado con la modelo Juliana Giambroni<\/b>, con quien tuvo dos hijos, Olivia y Milo. A continuaci\u00f3n, entre 2016 y 2020, <b>mantuvo una relaci\u00f3n con Camila Cavallo, madre de su hija menor, Alma, nacida en 2017.<\/b><\/p>\n<p>Ac\u00e1, los momentos m\u00e1s destacados de la entrevista:<\/p>\n<p><b>\u2014\u00a1Recibimos a Mariano Mart\u00ednez, que adem\u00e1s est\u00e1 haciendo teatro, <\/b><i><b>Ni media palabra<\/b><\/i><b>, un \u00e9xito total! Contame un poco la experiencia del contacto con la gente, porque damos por sentado que uno se acostumbr\u00f3 despu\u00e9s de tantos a\u00f1os, pero sigue generando esas mariposas en la panza, \u00bfo no?&#8230;<\/b><\/p>\n<p>\u2014S\u00ed, claro, genera. A m\u00ed me encanta el cari\u00f1o de la gente, revalidar eso. Con Nico nos sorprendimos gr\u00e1tamente de ver c\u00f3mo a la gente le gusta vernos juntos otra vez; los dos juntos pasamos a ser como Carozo y Narizota<i>.<\/i>..<\/p>\n<p><b>-Es que hay todo una generaci\u00f3n que fue marcada por esa dupla&#8230;<\/b><\/p>\n<p>\u2014Total, y esa gente que nos ve\u00eda cuando eran j\u00f3venes como nosotros traen a sus hijos y les muestran de qu\u00e9 se re\u00edan. Y la obra trata de eso, de pasar un buen rato, de que sea una fiesta. Es una fiesta. Est\u00e1 planteada as\u00ed y as\u00ed la recibe la gente. Est\u00e1 buen\u00edsima.<\/p>\n<h3>\u201c\u00bfMi coraz\u00f3n&#8230;? Estoy muy contento. Y la quiero cuidar mucho de lo medi\u00e1tico: a ella y la mayor\u00eda de mi vida personal y privada\u00bb<\/h3>\n<p><b>\u2014\u00bfY est\u00e1s con el coraz\u00f3n ocupado? <\/b><\/p>\n<p>\u2014Estoy en paz, estoy muy contento. <\/p>\n<p><b>\u2014\u00bfTe cuesta contar? \u00bfQuer\u00e9s cuidar un poco esta relaci\u00f3n de lo medi\u00e1tico? <\/b><\/p>\n<p>\u2014S\u00ed, la quiero cuidar mucho de lo medi\u00e1tico, totalmente. Pero todo, eh, y la mayor\u00eda de mi vida personal y privada. <\/p>\n<p><b>\u2014\u00bfPero a eventos s\u00ed pod\u00e9s ir acompa\u00f1ado? <\/b><\/p>\n<p>\u2014Ya fui acompa\u00f1ado. Obviamente me puede acompa\u00f1ar porque es parte de la vida. Pero estar explay\u00e1ndome en mi intimidad, no&#8230; <\/p>\n<p><b>\u2014Claro, no hacer un reality desde casa&#8230; <\/b><\/p>\n<p>\u2014Ni siquiera explay\u00e1ndome en un textual, \u00bfeh? <\/p>\n<p><b>\u2014Ah, \u00bftanto as\u00ed? <\/b><\/p>\n<p>\u2014S\u00ed, s\u00ed, as\u00ed. <\/p>\n<p><b>\u2014\u00bfY por qu\u00e9 cerrar as\u00ed la puerta <\/b><\/p>\n<p>\u2014Porque me parece supersano. <\/p>\n<p><b>\u2014Ah, \u00bfs\u00ed? <\/b><\/p>\n<p>\u2014As\u00ed se cuida mucho m\u00e1s, porque la verdad que no me hace bien, no me funcion\u00f3 jam\u00e1s en la vida. Es una decisi\u00f3n que tom\u00e9. <\/p>\n<p><b>\u2014\u00bfVos sos de amor a primera vista <\/b><\/p>\n<p>\u2014No, no precisamente. <\/p>\n<p><b>\u2014Ah, no siempre. <\/b><\/p>\n<p>\u2014No. <\/p>\n<h3>\u2033Tengo la mejor onda con Mati, el padrastro de mis hijos\u00bb<\/h3>\n<p><b>\u2014Con las ex, \u00bfc\u00f3mo te llev\u00e1s? <\/b><\/p>\n<p>\u2014Bien, como te digo, me gusta siempre buscarle el lado bueno a las cosas. <\/p>\n<p><b>\u2014Viste que hay comunicaci\u00f3n pr\u00e1cticamente todos los d\u00edas. <\/b><\/p>\n<p>\u2014Y s\u00ed. Lo importante son los chicos, siempre. <\/p>\n<p><b>\u2014\u00bfAlgo que hac\u00e9s ahora que no te imaginaste que ibas a hacer? Yo paso Navidades y A\u00f1os Nuevos con todos: ex, familiares, todos. <\/b><\/p>\n<p>\u2014Obviamente, buena onda. Yo tengo la mejor onda con Mati, que es el padrastro de mis hijos, y es un tipazo. He ido a comer con \u00e9l. Despu\u00e9s, s\u00ed, obviamente cada uno tiene su vida y cada uno tiene su c\u00edrculo. <\/p>\n<p><b>\u2014Y s\u00ed, si los chicos tienen fiebre, capaz que el remedio se lo da \u00e9l, \u00bfviste? O va a buscarlo al colegio&#8230; <\/b><\/p>\n<p>\u2014Obvio, de hecho, hoy mis hijos m\u00e1s grandes viven con \u00e9l. Me parece s\u00faper importante tener buena onda y buena relaci\u00f3n. <\/p>\n<p><b>\u2014Y s\u00ed, porque es nuestro tesoro m\u00e1s grande. <\/b><\/p>\n<p>\u2014S\u00ed, es nuestro tesoro m\u00e1s grande.<\/p>\n<h3>\u201cYo creo que parte de mi timidez pasaba porque no encajaba, y en esa \u00e9poca no se sab\u00eda de la dislexia\u201d<\/h3>\n<p>\u2014Yo creo que parte de mi timidez pasaba porque no encajaba, y en esa \u00e9poca no se sab\u00eda de la dislexia. Y era el t\u00edpico: \u201cUh, sos un vago\u201d. \u201cUh, no te da\u201d. \u201cUh, no s\u00e9 qu\u00e9&#8230;\u201d. Y a la vez, jam\u00e1s contaba que a m\u00ed me gustaba actuar porque en mi familia no consideraban que yo pudiese tener las condiciones para hacerlo, \u00bfviste? Porque era recontra introvertido, t\u00edmido a un nivel doloroso. Leo \u2014me encanta leer\u2014 y a veces tengo dudas de ortograf\u00eda que digo: \u201cNo, mmm, bueno, y ya est\u00e1\u201d. <\/p>\n<p><b>\u2014\u00bfHasta el d\u00eda de hoy? <\/b><\/p>\n<p>\u2014Hasta el d\u00eda de hoy. Y de hecho, las tablas, por m\u00e1s de que me las estudie de memoria, a los tres minutos se me olvidan, digamos, porque es parte de la dislexia. <\/p>\n<p><b>\u2014Yo tengo muchos furcios. Me confundo&#8230; <\/b><\/p>\n<p>\u2014Yo tambi\u00e9n. <\/p>\n<p><b>\u2014&#8230;los nombres de los invitados. <\/b><\/p>\n<p>\u2014<i>(R\u00ede) <\/i>Es lo mismo. <\/p>\n<p><b>\u2014Me confundo los nombres de los hijos de los invitados y me pongo toda colorada y tengo casi cincuenta a\u00f1os. Ahora le agarr\u00e9 cari\u00f1o a mis errores, dije&#8230;<\/b><\/p>\n<p>\u2014Claro, tal cual. <\/p>\n<p><b>\u2014&#8230;son parte de m\u00ed, ya me r\u00edo, lo digo en c\u00e1mara. <\/b><\/p>\n<p>\u2014Yo, cuando tenga que hacer un PNT, y tenga que leerlo, pas\u00e1melo antes, \u00a1te lo pido por favor! En el tema dislexia hay que seguir trabajando para que el sistema se adapte al cien por cien. S\u00e9 que de a poco los colegios se van aggiornando, van haciendo lo que tienen que hacer, porque si no frustr\u00e1s a los chicos. Y eso despu\u00e9s deriva en un mont\u00f3n de cosas que no est\u00e1n buenas, y que pueden ser muy graves. <\/p>\n<p><b>\u2014Claro, est\u00e1 el abandono del colegio de muchos chicos por falta de autoestima&#8230;<\/b><\/p>\n<p>\u2014Claro, o buscar validaci\u00f3n en cosas que no est\u00e1n buenas, que habr\u00eda que decirlas, \u00bfno? En la droga, en el vandalismo. <\/p>\n<p><b>\u2014Lamentablemente hay muchos que se dan por perdidos y se rinden en el camino. <\/b><\/p>\n<p>\u2014Claro, y la pasan muy mal y son juzgados por sus pares, por su grupo de pertenencia y a veces buscan la aprobaci\u00f3n desde la rebeld\u00eda extrema, \u00bfviste?<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-3.jpg\" alt=\"\"En el tema dislexia hay que seguir trabajando para que el sistema se adapte al cien por cien. S\u00e9 que de a poco los colegios se van aggiornando, van haciendo lo que tienen que hacer, porque si no frustr\u00e1s a los chicos. Y eso despu\u00e9s deriva en un mont\u00f3n de cosas que no est\u00e1n buenas, y que pueden ser muy graves\", afirma, categ\u00f3rico \" height=\"2048\" width=\"1363\"\/><\/p>\n<h3>\u201cSiento que puedo ser un padre cien por cien y no traer cosas del pasado\u201d<\/h3>\n<p><b>\u2014Cuando fuiste pap\u00e1, \u00bfpudiste ver a tus pap\u00e1s de una manera distinta Porque en tu caso fueron padres muy j\u00f3venes. \u00bfQu\u00e9 ten\u00edan, diecis\u00e9is, diecisiete a\u00f1os, no? <\/b><\/p>\n<p>\u2014Mis padres, s\u00ed, diecis\u00e9is. Muy ni\u00f1os. <\/p>\n<p><b>\u2014Reci\u00e9n cuando uno es pap\u00e1 hace el clic, \u00bfno? <\/b><\/p>\n<p>\u2014S\u00ed, obvio, los entend\u00ed en muchos aspectos&#8230; Los perdon\u00e9 en lo que hicieron mal tambi\u00e9n&#8230; porque me parec\u00eda absolutamente necesario para poder evolucionar, \u00bfviste? Y poder transmitirle cosas buenas a mis hijos. Si no perdonaba a mis pap\u00e1s, jam\u00e1s iba a poder hacerlo. <\/p>\n<p><b>\u2014\u00bfC\u00f3mo fueron como pap\u00e1s siendo tan chiquitos los dos? <\/b><\/p>\n<p>\u2014Mi mam\u00e1 siempre fue muy amorosa, y mi viejo, a su manera, tambi\u00e9n, siempre queriendo dar lo mejor. Obviamente, esto de ser chicos&#8230; ellos tambi\u00e9n tra\u00edan cosas de sus padres: si bien mi viejo tuvo a sus padres representes, tambi\u00e9n tuvo sus cosas, pero mi mam\u00e1 tuvo una vida bastante dif\u00edcil de chiquita; la madre se fue cuando ella era muy chica: volv\u00eda, se volv\u00eda a ir, \u00bfviste? Como que hubo&#8230; <\/p>\n<p><b>\u2014Mucho abandono. <\/b><\/p>\n<p>\u2014S\u00ed, fue muy doloroso para ella. Por ser tan chiquita, siempre me dec\u00eda: \u201cVos sos como un hermano para m\u00ed\u201d <i>(risas). <\/i><\/p>\n<p><b>\u2014Claro, porque fueron creciendo juntos&#8230; <\/b><\/p>\n<p>\u2014Claro, fuimos creciendo juntos, pero en un punto yo no era el hermano, \u00bfviste? Pero siempre estuvo muy presente, al pie del ca\u00f1\u00f3n, y siempre me cuid\u00f3 mucho&#8230; Con las herramientas que ten\u00eda y eso yo lo valoro valoro much\u00edsimo. Es una gran persona mi mam\u00e1 y mi pap\u00e1 tambi\u00e9n, claramente. Pero de un tiempo no tan lejano a esta parte yo ya me siento liberado de todo eso. Siento que puedo ser un padre cien por cien y no traer cosas del pasado, \u00bfviste? Me parece muy importante trabajar eso. Obviamente no es f\u00e1cil, pero yo te digo que se puede hacer. Y para eso, para cortar ciertas cadenas, es reimportante ser perseverante. <\/p>\n<p><b>\u2014\u00bfQu\u00e9 te ayud\u00f3 para entender? \u00bfTerapia, fe, evolucionar, tus propios porrazos? <\/b><\/p>\n<p>\u2014Muchos golpes<\/p>\n<h3>\u00bfQu\u00e9 dice la gente sobre Mariano Mart\u00ednez?<\/h3>\n<p><b>\u2014Desde el 2020 hiciste videos bailando, que fueron muy virales. Tengo ac\u00e1 alg\u00fan comentarios que te han puesto en las redes. \u201c\u00a1Alguien que le saque el TikTok a Mariano Mart\u00ednez, por favor!\u201d. <\/b><\/p>\n<p><i>\u2014(R\u00ede) <\/i>Eso lo puede haber dicho Rulo (Schijman), mi amigo, que me critica. <\/p>\n<p><b>\u2014\u00a1Ay, esta me da ternura! \u201c\u00bfPor qu\u00e9 mi marido no se ve as\u00ed? Me falt\u00f3 m\u00e1s fe, padre Tom\u00e1s\u201d. <\/b><\/p>\n<p><i>\u2014(R\u00ede).<\/i>.. <\/p>\n<p><b>\u2014Otra: \u201cCincuenta y seis a\u00f1itos tiene esa criatura y bastante&#8230;\u201d <\/b><\/p>\n<p>\u2014\u00a1Cincuenta y seis, me mat\u00f3! <i>(R\u00ede).<\/i> Tengo cuarenta y siete.<b> <\/b>A m\u00ed me causa mucha gracia los comentarios que quieren hacer como para herir&#8230; A veces miro, aunque generalmente no. Siento que habla m\u00e1s de ellos que de m\u00ed cien por cien. Y despu\u00e9s tambi\u00e9n los halagos los recibo con mucho amor, pero tampoco me los creo. Es como que siento que uno tiene que estar con los pies sobre la tierra. Siento que traspas\u00e9 como una barrera de todo lo que me puedan llegar a decir&#8230; <\/p>\n<p><b>\u2014Ya no hay prejuicio de nada&#8230; <\/b><\/p>\n<p>\u2014No, no. Sinceramente, me resbala. <\/p>\n<p><b>\u2014Te digo algunos m\u00e1s: \u201c\u00bfSos Wi-Fi? Porque siento una conexi\u00f3n tremenda\u201d..<\/b><\/p>\n<p>\u2014<i>(R\u00ede)<\/i> \u00a1Qu\u00e9 bien esa, me la voy a escribir! <\/p>\n<p><b>\u2014\u00bfTe han encarado las mujeres as\u00ed en redes? <\/b><\/p>\n<p>\u2014Pasa, s\u00ed, pasa, pasa. <\/p>\n<p><b>\u2014\u00bfY te pon\u00edas a charlar? <\/b><\/p>\n<p>\u2014A veces s\u00ed, obvio. <\/p>\n<p><b>\u2014\u00bfPor qu\u00e9 no? <\/b><\/p>\n<p>\u2014Claro. <\/p>\n<p><b>\u2014Somos humanos. <\/b><\/p>\n<p>\u2014S\u00ed, total.<\/p>\n<h3>\u201cNo tomo alcohol, tomo mucha ag\u00fcita\u201d<\/h3>\n<p>\u2014Quiero vivir hasta los ciento once a\u00f1os <i>(r\u00ede).<\/i>.. <\/p>\n<p><b>\u2014\u00bfTe cuid\u00e1s mucho? \u00bfCon remedios, con cosas&#8230;? <\/b><\/p>\n<p>\u2014No, como sano, tomo mucha agua. Para que tome algo de alcohol, un vinito o algo, tiene que ser muy especial la ocasi\u00f3n.<\/p>\n<p><b>\u2014\u00bfEn una cita rom\u00e1ntica <\/b><\/p>\n<p>\u2014Pero \u00bfsab\u00e9s qu\u00e9? No me hace falta. Yo con el agua te conquisto<i> (r\u00ede).<\/i> Bailo, me encanta bailar. O sea, parece por ah\u00ed que estoy tomado, pero no. Me gusta mucho bailar y lo puedo hacer con agua, tanto que me dicen: \u201cNo, \u00bfc\u00f3mo hace?\u201c No s\u00e9. Y yo noto c\u00f3mo mis amigos se empiezan a deteriorar, \u00bfviste? <\/p>\n<p><b>\u2014Y vos segu\u00eds ah\u00ed arriba. <\/b><\/p>\n<p>\u2014Yo sigo arriba, pero con ag\u00fcita. <\/p>\n<p><b>\u2014Con el agua te ech\u00e1s cuatro bailes, la romp\u00e9s. \u00bfQu\u00e9 ritmo de baile te gusta <\/b><\/p>\n<p>\u2014Me gusta Luis Miguel. Justin Bieber me encanta y compartimos con mi hija ese gusto; lo conoc\u00ed cuando \u00e9l estuvo ac\u00e1 en Argentina. <\/p>\n<p><b>\u2014\u00bfC\u00f3mo es la an\u00e9cdota con \u00e9l? <\/b><\/p>\n<p>\u2014Pas\u00f3 que cuando vino a Argentina, la hija de un conocido de Avellaneda ten\u00eda leucemia&#8230; <\/p>\n<p><b>\u2014Oh. <\/b><\/p>\n<p>\u2014Y este amigo me llama para decirme que el sue\u00f1o de ella era conocer a Justin Bieber, si pod\u00eda hacer algo. Y est\u00e1bamos ah\u00ed esperando para hacer el <i>meet and greet<\/i>, pero Justin no estaba bien, \u00bfviste? Nosotros pensamos que no iba a salir, la verdad. Y nada&#8230; vamos a un lugar resguardado para poder ver y \u00e9l empieza el show y lo vimos como: \u201c\u00a1Guau!\u201d, el pibe bailaba y cantaba de una manera incre\u00edble estando como lo vimos, pobre. Despu\u00e9s el recital se suspende y pas\u00f3 todo lo que pas\u00f3&#8230; Y como la chica con leucemia no hab\u00eda podido cumplir su sue\u00f1o&#8230; que lo quer\u00edan demonizar. <\/p>\n<p><b>\u2014Como si dejara de ser humano, \u00bfno? <\/b><\/p>\n<p>\u2014Claro, y yo lo defend\u00eda, porque es un ser humano, no es lindo para nadie meterse en esas cosas. <\/p>\n<p><b>\u2014\u00bfLa industria fue buena con vos? <\/b><\/p>\n<p>\u2014Fue, en otro nivel, obviamente cero de compararme. Yo ten\u00eda dieciocho a\u00f1os, en ese momento estaba como fanatizado&#8230; el dinero y mucha fama y todas las puertas abiertas, y con lo que a m\u00ed me hab\u00eda pasado de chico, fue bastante dif\u00edcil. Tuve que trabajar mucho en eso. No me cruc\u00e9 con la gente correcta. M\u00e1s all\u00e1 de la fama y todo lo bueno de poder lograr lo que logr\u00e9 con una novela, en lo personal no eran buenos momentos. <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-4.jpg\" alt=\"\"Tengo cuarenta y siete. A m\u00ed me causa mucha gracia los comentarios que quieren hacer como para herir... A veces miro las redes, aunque generalmente no. Siento que habla m\u00e1s de ellos que de m\u00ed cien por cien. Y despu\u00e9s tambi\u00e9n los halagos los recibo con mucho amor, pero tampoco me los creo. Uno tiene que estar con los pies sobre la tierra\", comenta sobre su eterna estampa de gal\u00e1n\" height=\"1363\" width=\"2048\"\/><\/p>\n<p><b>\u2014\u00bfY c\u00f3mo te rescataste? <\/b><\/p>\n<p>\u2014Tuve suerte. Tuve a Marcelo Rey, que era mi representante, que ya falleci\u00f3 hace mucho tiempo. Fue como un padre para m\u00ed, me educaba mucho, me conten\u00eda mucho pero as\u00ed y todo era complicado. Pobre, lo hice renegar un mont\u00f3n.<\/p>\n<p><i>Mir\u00e1 la entrevista completa en el video.<\/i><\/p>\n<p><i><b>Fotos: Candela Teicheira<\/b><\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mariano Mart\u00ednez \u20145 de diciembre de 1978, Buenos Aires\u2014 se consolid\u00f3 como una de las figuras m\u00e1s reconocibles de la televisi\u00f3n argentina gracias a una trayectoria que abarca m\u00e1s de dos d\u00e9cadas en distintos formatos, desde telenovelas hasta teatro y cine, y por la obtenci\u00f3n de galardones que evidencian su llegada al p\u00fablico m\u00e1s joven&#8230;.<\/p>\n","protected":false},"author":1,"featured_media":53281,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[79],"tags":[],"class_list":["post-53272","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cine-y-series"],"magazineBlocksPostFeaturedMedia":{"thumbnail":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-7-150x150.jpg","medium":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-7-300x200.jpg","medium_large":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-7-768x511.jpg","large":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-7-1024x682.jpg","1536x1536":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-7-1536x1022.jpg","2048x2048":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-7.jpg","newsmatic-featured":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-7-820x545.jpg","newsmatic-list":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-7-600x400.jpg","newsmatic-thumb":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-7-300x200.jpg","newsmatic-small":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-7-150x95.jpg","newsmatic-grid":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-7-400x250.jpg"},"magazineBlocksPostAuthor":{"name":"admin","avatar":"https:\/\/secure.gravatar.com\/avatar\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":"0","magazineBlocksPostExcerpt":"Mariano Mart\u00ednez \u20145 de diciembre de 1978, Buenos Aires\u2014 se consolid\u00f3 como una de las figuras m\u00e1s reconocibles de la televisi\u00f3n argentina gracias a una trayectoria que abarca m\u00e1s de dos d\u00e9cadas en distintos formatos, desde telenovelas hasta teatro y cine, y por la obtenci\u00f3n de galardones que evidencian su llegada al p\u00fablico m\u00e1s joven....","magazineBlocksPostCategories":["Cine y Series"],"magazineBlocksPostViewCount":10,"magazineBlocksPostReadTime":13,"magazine_blocks_featured_image_url":{"full":["https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-7.jpg",2048,1363,false],"medium":["https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-7-300x200.jpg",300,200,true],"thumbnail":["https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-7-150x150.jpg",150,150,true]},"magazine_blocks_author":{"display_name":"admin","author_link":"https:\/\/lobosnews.com.ar\/index.php\/author\/lobos-news\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-79\">Cine y Series<\/a>","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mariano Mart\u00ednez en \u201cLo de Pampita\u201d: \u201cQuiero cuidar mi relaci\u00f3n de lo medi\u00e1tico\u201d - Lobos News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mariano Mart\u00ednez en \u201cLo de Pampita\u201d: \u201cQuiero cuidar mi relaci\u00f3n de lo medi\u00e1tico\u201d - Lobos News\" \/>\n<meta property=\"og:description\" content=\"Mariano Mart\u00ednez \u20145 de diciembre de 1978, Buenos Aires\u2014 se consolid\u00f3 como una de las figuras m\u00e1s reconocibles de la televisi\u00f3n argentina gracias a una trayectoria que abarca m\u00e1s de dos d\u00e9cadas en distintos formatos, desde telenovelas hasta teatro y cine, y por la obtenci\u00f3n de galardones que evidencian su llegada al p\u00fablico m\u00e1s joven....\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Lobos News\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T05:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T06:40:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico.jpg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-2\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/lobosnews.com.ar\/#\/schema\/person\/232422a593d5c541dd9aef6aaed10943\"},\"headline\":\"Mariano Mart\u00ednez en \u201cLo de Pampita\u201d: \u201cQuiero cuidar mi relaci\u00f3n de lo medi\u00e1tico\u201d\",\"datePublished\":\"2026-05-13T05:00:00+00:00\",\"dateModified\":\"2026-05-13T06:40:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-2\/\"},\"wordCount\":2478,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/lobosnews.com.ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-7.jpg\",\"articleSection\":[\"Cine y Series\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-2\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-2\/\",\"url\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-2\/\",\"name\":\"Mariano Mart\u00ednez en \u201cLo de Pampita\u201d: \u201cQuiero cuidar mi relaci\u00f3n de lo medi\u00e1tico\u201d - Lobos News\",\"isPartOf\":{\"@id\":\"https:\/\/lobosnews.com.ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-7.jpg\",\"datePublished\":\"2026-05-13T05:00:00+00:00\",\"dateModified\":\"2026-05-13T06:40:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-2\/#primaryimage\",\"url\":\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-7.jpg\",\"contentUrl\":\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-7.jpg\",\"width\":2048,\"height\":1363,\"caption\":\"Mariano Mart\u00ednez en \u201cLo de Pampita\u201d: \u201cQuiero cuidar mi relaci\u00f3n de lo medi\u00e1tico\u201d\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/lobosnews.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mariano Mart\u00ednez en \u201cLo de Pampita\u201d: \u201cQuiero cuidar mi relaci\u00f3n de lo medi\u00e1tico\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lobosnews.com.ar\/#website\",\"url\":\"https:\/\/lobosnews.com.ar\/\",\"name\":\"Lobos News\",\"description\":\"Informaci\u00f3n a cada instante\",\"publisher\":{\"@id\":\"https:\/\/lobosnews.com.ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lobosnews.com.ar\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/lobosnews.com.ar\/#organization\",\"name\":\"Lobos News\",\"url\":\"https:\/\/lobosnews.com.ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/lobosnews.com.ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/01\/logo-lobosnews.png\",\"contentUrl\":\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/01\/logo-lobosnews.png\",\"width\":500,\"height\":200,\"caption\":\"Lobos News\"},\"image\":{\"@id\":\"https:\/\/lobosnews.com.ar\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/lobosnews.com.ar\/#\/schema\/person\/232422a593d5c541dd9aef6aaed10943\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/lobosnews.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/lobosnews.com.ar\"],\"url\":\"https:\/\/lobosnews.com.ar\/index.php\/author\/lobos-news\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mariano Mart\u00ednez en \u201cLo de Pampita\u201d: \u201cQuiero cuidar mi relaci\u00f3n de lo medi\u00e1tico\u201d - Lobos News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-2\/","og_locale":"es_ES","og_type":"article","og_title":"Mariano Mart\u00ednez en \u201cLo de Pampita\u201d: \u201cQuiero cuidar mi relaci\u00f3n de lo medi\u00e1tico\u201d - Lobos News","og_description":"Mariano Mart\u00ednez \u20145 de diciembre de 1978, Buenos Aires\u2014 se consolid\u00f3 como una de las figuras m\u00e1s reconocibles de la televisi\u00f3n argentina gracias a una trayectoria que abarca m\u00e1s de dos d\u00e9cadas en distintos formatos, desde telenovelas hasta teatro y cine, y por la obtenci\u00f3n de galardones que evidencian su llegada al p\u00fablico m\u00e1s joven....","og_url":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-2\/","og_site_name":"Lobos News","article_published_time":"2026-05-13T05:00:00+00:00","article_modified_time":"2026-05-13T06:40:27+00:00","og_image":[{"url":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico.jpg","type":"","width":"","height":""}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-2\/#article","isPartOf":{"@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-2\/"},"author":{"name":"admin","@id":"https:\/\/lobosnews.com.ar\/#\/schema\/person\/232422a593d5c541dd9aef6aaed10943"},"headline":"Mariano Mart\u00ednez en \u201cLo de Pampita\u201d: \u201cQuiero cuidar mi relaci\u00f3n de lo medi\u00e1tico\u201d","datePublished":"2026-05-13T05:00:00+00:00","dateModified":"2026-05-13T06:40:27+00:00","mainEntityOfPage":{"@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-2\/"},"wordCount":2478,"commentCount":0,"publisher":{"@id":"https:\/\/lobosnews.com.ar\/#organization"},"image":{"@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-2\/#primaryimage"},"thumbnailUrl":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-7.jpg","articleSection":["Cine y Series"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-2\/","url":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-2\/","name":"Mariano Mart\u00ednez en \u201cLo de Pampita\u201d: \u201cQuiero cuidar mi relaci\u00f3n de lo medi\u00e1tico\u201d - Lobos News","isPartOf":{"@id":"https:\/\/lobosnews.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-2\/#primaryimage"},"image":{"@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-2\/#primaryimage"},"thumbnailUrl":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-7.jpg","datePublished":"2026-05-13T05:00:00+00:00","dateModified":"2026-05-13T06:40:27+00:00","breadcrumb":{"@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-2\/#primaryimage","url":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-7.jpg","contentUrl":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-7.jpg","width":2048,"height":1363,"caption":"Mariano Mart\u00ednez en \u201cLo de Pampita\u201d: \u201cQuiero cuidar mi relaci\u00f3n de lo medi\u00e1tico\u201d"},{"@type":"BreadcrumbList","@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lobosnews.com.ar\/"},{"@type":"ListItem","position":2,"name":"Mariano Mart\u00ednez en \u201cLo de Pampita\u201d: \u201cQuiero cuidar mi relaci\u00f3n de lo medi\u00e1tico\u201d"}]},{"@type":"WebSite","@id":"https:\/\/lobosnews.com.ar\/#website","url":"https:\/\/lobosnews.com.ar\/","name":"Lobos News","description":"Informaci\u00f3n a cada instante","publisher":{"@id":"https:\/\/lobosnews.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lobosnews.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/lobosnews.com.ar\/#organization","name":"Lobos News","url":"https:\/\/lobosnews.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lobosnews.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/01\/logo-lobosnews.png","contentUrl":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/01\/logo-lobosnews.png","width":500,"height":200,"caption":"Lobos News"},"image":{"@id":"https:\/\/lobosnews.com.ar\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/lobosnews.com.ar\/#\/schema\/person\/232422a593d5c541dd9aef6aaed10943","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lobosnews.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/lobosnews.com.ar"],"url":"https:\/\/lobosnews.com.ar\/index.php\/author\/lobos-news\/"}]}},"jetpack_featured_media_url":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/mariano-martinez-en-lo-de-pampita-quiero-cuidar-mi-relacion-de-lo-mediatico-7.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/53272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=53272"}],"version-history":[{"count":1,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/53272\/revisions"}],"predecessor-version":[{"id":53280,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/53272\/revisions\/53280"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/media\/53281"}],"wp:attachment":[{"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=53272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=53272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=53272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}