{"id":53162,"date":"2026-05-13T00:15:20","date_gmt":"2026-05-13T00:15:20","guid":{"rendered":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella\/"},"modified":"2026-05-13T00:38:47","modified_gmt":"2026-05-13T00:38:47","slug":"yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella","status":"publish","type":"post","link":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella\/","title":{"rendered":"Yanina Latorre revel\u00f3 que Wanda Nara tendr\u00eda un nuevo novio, famoso y m\u00e1s joven que ella"},"content":{"rendered":"<p><span class=\"waslinkname\"><b>Wanda Nara<\/b><\/span> volvi\u00f3 a ser el centro de la escena y, fiel a su estilo, no deja de sorprender con cada movimiento en su vida sentimental. En los \u00faltimos minutos, <span class=\"waslinkname\"><b>Yanina Latorre<\/b><\/span> lanz\u00f3 una bomba en la televisi\u00f3n y asegur\u00f3 que la empresaria y conductora <b>ya habr\u00eda pasado p\u00e1gina tras su separaci\u00f3n de <\/b><span class=\"waslinkname\"><b>Mart\u00edn Migueles<\/b><\/span>: estar\u00eda saliendo con un nuevo y famoso novio, m\u00e1s joven que ella y con pasado en el mundo del espect\u00e1culo.<\/p>\n<p>El rumor llega en medio de uno de los momentos m\u00e1s agitados de la vida de Wanda. La empresaria <b>confirm\u00f3 p\u00fablicamente su ruptura con Migueles, apenas se conoci\u00f3 la citaci\u00f3n judicial del empresario<\/b> en una compleja causa por maniobras financieras, y volvi\u00f3 a instalarse como protagonista de los titulares. Mientras la Justicia avanzaba con la investigaci\u00f3n y Migueles se presentaba en Comodoro Py, Wanda apur\u00f3 los tiempos y <b>anunci\u00f3 que hac\u00eda un mes que estaban separados.<\/b> Sin embargo, Yanina Latorre desminti\u00f3 esa versi\u00f3n y desliz\u00f3 que la ruptura fue mucho m\u00e1s reciente y directamente relacionada con el esc\u00e1ndalo judicial.<\/p>\n<p><b>\u201cA m\u00ed me dijeron que tiene chongo nuevo\u201d<\/b>, lanz\u00f3 Yanina en <i>SQP<\/i> (Am\u00e9rica TV), dejando en claro que la informaci\u00f3n no proven\u00eda del entorno de Wanda, sino de otras fuentes vinculadas al ambiente. La periodista fue a\u00fan m\u00e1s all\u00e1 y sembr\u00f3 dudas sobre la cronolog\u00eda de los hechos:<b> \u201cMe dijeron que es mentira que hace un mes est\u00e1 separada y que lo raj\u00f3 por el l\u00edo judicial\u201d.<\/b><\/p>\n<p>El misterio sobre la identidad del supuesto nuevo novio no dur\u00f3 demasiado. Aunque Latorre prefiri\u00f3 no dar todos los datos hasta que Wanda se lo confirme, dio pistas concretas: \u201c<b>Es demasiado prolijo. No tiene hijos, es pendejo, es m\u00e1s chico, pero tampoco tiene 18. <\/b>Yo en alg\u00fan momento me relacion\u00e9 con \u00e9l, viaj\u00e9 una vez en avi\u00f3n con \u00e9l. Es del mundo del espect\u00e1culo. No es un se\u00f1or ni tiene problemas con la Justicia, <b>es limpio, es lindo y me tiene miedo a m\u00ed<\/b>\u201d, brome\u00f3, dejando en claro que el joven tiene un perfil muy distinto al de sus exparejas m\u00e1s recientes.<\/p>\n<p>Las especulaciones no tardaron en multiplicarse hasta que Yanina lo confirm\u00f3: <span class=\"waslinkname\"><b>Agust\u00edn Bernasconi<\/b><\/span>. El actor y cantante, que actualmente comparte elenco con Wanda en la pel\u00edcula \u201c\u00bfQuer\u00e9s ser mi hijo?\u201d, habr\u00eda sido el elegido por la empresaria para empezar una nueva historia despu\u00e9s de la tormenta con Migueles. \u201c<b>Wanda se est\u00e1 emp&#8230;, desde que est\u00e1 en Uruguay, a Agust\u00edn Bernasconi. Hay que ver si \u00e9l se anima a blanquear p\u00fablicamente. <\/b>Ella dice que nunca estuvieron antes y qued\u00f3 esa calentura. Eso fue lo que lo enoj\u00f3 a Migueles y se terminaron de pelear. Hay escenas de sexo en la pel\u00edcula y parece que, despu\u00e9s de grabar, siguieron\u201d, revel\u00f3 Latorre, aumentando la expectativa por una posible confirmaci\u00f3n.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella.jpg\" alt=\"Agust\u00edn Bernasconi fue se\u00f1alado como el supuesto nuevo novio de Wanda Nara seg\u00fan la informaci\u00f3n confirmada por Yanina Latorre\" height=\"1920\" width=\"1440\"\/><\/p>\n<p>La informaci\u00f3n llega <b>justo cuando Wanda Nara est\u00e1 filmando la comedia rom\u00e1ntica en Uruguay, donde comparte protagonismo con Bernasconi.<\/b> Seg\u00fan detall\u00f3 la animadora, el acercamiento entre ambos se habr\u00eda dado durante las largas jornadas de rodaje y ensayo, y la qu\u00edmica traspas\u00f3 la pantalla. \u201cSon superprofesionales, ensayan de noche con los compa\u00f1eros, no comparten momentos solos\u2026 <b>Pero parece que despu\u00e9s de grabar, siguieron<\/b>\u201d, agreg\u00f3, dando a entender que el v\u00ednculo habr\u00eda evolucionado fuera del set.<\/p>\n<p>Adem\u00e1s, la presentadora especul\u00f3 al aire con la posibilidad de que ambos asistan juntos a los Premios Mart\u00edn Fierro, que se celebrar\u00e1n el pr\u00f3ximo lunes en Buenos Aires. <b>\u201cEs capaz\u201d<\/b>, respondi\u00f3 Yanina, ante la consulta de su panelista P\u00eda Shaw. <b>\u201cHay que ver si \u00e9l se anima a blanquear p\u00fablicamente que le est\u00e1 visitando la cueva\u201d<\/b>, continu\u00f3, antes de haber revelado el nombre del joven actor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wanda Nara volvi\u00f3 a ser el centro de la escena y, fiel a su estilo, no deja de sorprender con cada movimiento en su vida sentimental. En los \u00faltimos minutos, Yanina Latorre lanz\u00f3 una bomba en la televisi\u00f3n y asegur\u00f3 que la empresaria y conductora ya habr\u00eda pasado p\u00e1gina tras su separaci\u00f3n de Mart\u00edn Migueles:&#8230;<\/p>\n","protected":false},"author":1,"featured_media":53165,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[79],"tags":[],"class_list":["post-53162","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cine-y-series"],"magazineBlocksPostFeaturedMedia":{"thumbnail":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella-150x150.jpg","medium":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella-225x300.jpg","medium_large":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella-768x1024.jpg","large":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella-768x1024.jpg","1536x1536":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella-1152x1536.jpg","2048x2048":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella.jpg","newsmatic-featured":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella-820x545.jpg","newsmatic-list":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella-600x400.jpg","newsmatic-thumb":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella-300x200.jpg","newsmatic-small":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella-150x95.jpg","newsmatic-grid":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella-400x250.jpg"},"magazineBlocksPostAuthor":{"name":"admin","avatar":"https:\/\/secure.gravatar.com\/avatar\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":"0","magazineBlocksPostExcerpt":"Wanda Nara volvi\u00f3 a ser el centro de la escena y, fiel a su estilo, no deja de sorprender con cada movimiento en su vida sentimental. En los \u00faltimos minutos, Yanina Latorre lanz\u00f3 una bomba en la televisi\u00f3n y asegur\u00f3 que la empresaria y conductora ya habr\u00eda pasado p\u00e1gina tras su separaci\u00f3n de Mart\u00edn Migueles:...","magazineBlocksPostCategories":["Cine y Series"],"magazineBlocksPostViewCount":8,"magazineBlocksPostReadTime":4,"magazine_blocks_featured_image_url":{"full":["https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella.jpg",1440,1920,false],"medium":["https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella-225x300.jpg",225,300,true],"thumbnail":["https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella-150x150.jpg",150,150,true]},"magazine_blocks_author":{"display_name":"admin","author_link":"https:\/\/lobosnews.com.ar\/index.php\/author\/lobos-news\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-79\">Cine y Series<\/a>","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Yanina Latorre revel\u00f3 que Wanda Nara tendr\u00eda un nuevo novio, famoso y m\u00e1s joven que ella - Lobos News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Yanina Latorre revel\u00f3 que Wanda Nara tendr\u00eda un nuevo novio, famoso y m\u00e1s joven que ella - Lobos News\" \/>\n<meta property=\"og:description\" content=\"Wanda Nara volvi\u00f3 a ser el centro de la escena y, fiel a su estilo, no deja de sorprender con cada movimiento en su vida sentimental. En los \u00faltimos minutos, Yanina Latorre lanz\u00f3 una bomba en la televisi\u00f3n y asegur\u00f3 que la empresaria y conductora ya habr\u00eda pasado p\u00e1gina tras su separaci\u00f3n de Mart\u00edn Migueles:...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella\/\" \/>\n<meta property=\"og:site_name\" content=\"Lobos News\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T00:15:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T00:38:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella.jpg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/lobosnews.com.ar\/#\/schema\/person\/232422a593d5c541dd9aef6aaed10943\"},\"headline\":\"Yanina Latorre revel\u00f3 que Wanda Nara tendr\u00eda un nuevo novio, famoso y m\u00e1s joven que ella\",\"datePublished\":\"2026-05-13T00:15:20+00:00\",\"dateModified\":\"2026-05-13T00:38:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella\/\"},\"wordCount\":671,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/lobosnews.com.ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella.jpg\",\"articleSection\":[\"Cine y Series\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella\/\",\"url\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella\/\",\"name\":\"Yanina Latorre revel\u00f3 que Wanda Nara tendr\u00eda un nuevo novio, famoso y m\u00e1s joven que ella - Lobos News\",\"isPartOf\":{\"@id\":\"https:\/\/lobosnews.com.ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella.jpg\",\"datePublished\":\"2026-05-13T00:15:20+00:00\",\"dateModified\":\"2026-05-13T00:38:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella\/#primaryimage\",\"url\":\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella.jpg\",\"contentUrl\":\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella.jpg\",\"width\":1440,\"height\":1920,\"caption\":\"Yanina Latorre revel\u00f3 que Wanda Nara tendr\u00eda un nuevo novio, famoso y m\u00e1s joven que ella\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/lobosnews.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Yanina Latorre revel\u00f3 que Wanda Nara tendr\u00eda un nuevo novio, famoso y m\u00e1s joven que ella\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lobosnews.com.ar\/#website\",\"url\":\"https:\/\/lobosnews.com.ar\/\",\"name\":\"Lobos News\",\"description\":\"Informaci\u00f3n a cada instante\",\"publisher\":{\"@id\":\"https:\/\/lobosnews.com.ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lobosnews.com.ar\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/lobosnews.com.ar\/#organization\",\"name\":\"Lobos News\",\"url\":\"https:\/\/lobosnews.com.ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/lobosnews.com.ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/01\/logo-lobosnews.png\",\"contentUrl\":\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/01\/logo-lobosnews.png\",\"width\":500,\"height\":200,\"caption\":\"Lobos News\"},\"image\":{\"@id\":\"https:\/\/lobosnews.com.ar\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/lobosnews.com.ar\/#\/schema\/person\/232422a593d5c541dd9aef6aaed10943\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/lobosnews.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/lobosnews.com.ar\"],\"url\":\"https:\/\/lobosnews.com.ar\/index.php\/author\/lobos-news\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Yanina Latorre revel\u00f3 que Wanda Nara tendr\u00eda un nuevo novio, famoso y m\u00e1s joven que ella - Lobos News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella\/","og_locale":"es_ES","og_type":"article","og_title":"Yanina Latorre revel\u00f3 que Wanda Nara tendr\u00eda un nuevo novio, famoso y m\u00e1s joven que ella - Lobos News","og_description":"Wanda Nara volvi\u00f3 a ser el centro de la escena y, fiel a su estilo, no deja de sorprender con cada movimiento en su vida sentimental. En los \u00faltimos minutos, Yanina Latorre lanz\u00f3 una bomba en la televisi\u00f3n y asegur\u00f3 que la empresaria y conductora ya habr\u00eda pasado p\u00e1gina tras su separaci\u00f3n de Mart\u00edn Migueles:...","og_url":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella\/","og_site_name":"Lobos News","article_published_time":"2026-05-13T00:15:20+00:00","article_modified_time":"2026-05-13T00:38:47+00:00","og_image":[{"url":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella.jpg","type":"","width":"","height":""}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella\/#article","isPartOf":{"@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella\/"},"author":{"name":"admin","@id":"https:\/\/lobosnews.com.ar\/#\/schema\/person\/232422a593d5c541dd9aef6aaed10943"},"headline":"Yanina Latorre revel\u00f3 que Wanda Nara tendr\u00eda un nuevo novio, famoso y m\u00e1s joven que ella","datePublished":"2026-05-13T00:15:20+00:00","dateModified":"2026-05-13T00:38:47+00:00","mainEntityOfPage":{"@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella\/"},"wordCount":671,"commentCount":0,"publisher":{"@id":"https:\/\/lobosnews.com.ar\/#organization"},"image":{"@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella\/#primaryimage"},"thumbnailUrl":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella.jpg","articleSection":["Cine y Series"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella\/","url":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella\/","name":"Yanina Latorre revel\u00f3 que Wanda Nara tendr\u00eda un nuevo novio, famoso y m\u00e1s joven que ella - Lobos News","isPartOf":{"@id":"https:\/\/lobosnews.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella\/#primaryimage"},"image":{"@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella\/#primaryimage"},"thumbnailUrl":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella.jpg","datePublished":"2026-05-13T00:15:20+00:00","dateModified":"2026-05-13T00:38:47+00:00","breadcrumb":{"@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella\/#primaryimage","url":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella.jpg","contentUrl":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella.jpg","width":1440,"height":1920,"caption":"Yanina Latorre revel\u00f3 que Wanda Nara tendr\u00eda un nuevo novio, famoso y m\u00e1s joven que ella"},{"@type":"BreadcrumbList","@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/05\/13\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lobosnews.com.ar\/"},{"@type":"ListItem","position":2,"name":"Yanina Latorre revel\u00f3 que Wanda Nara tendr\u00eda un nuevo novio, famoso y m\u00e1s joven que ella"}]},{"@type":"WebSite","@id":"https:\/\/lobosnews.com.ar\/#website","url":"https:\/\/lobosnews.com.ar\/","name":"Lobos News","description":"Informaci\u00f3n a cada instante","publisher":{"@id":"https:\/\/lobosnews.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lobosnews.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/lobosnews.com.ar\/#organization","name":"Lobos News","url":"https:\/\/lobosnews.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lobosnews.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/01\/logo-lobosnews.png","contentUrl":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/01\/logo-lobosnews.png","width":500,"height":200,"caption":"Lobos News"},"image":{"@id":"https:\/\/lobosnews.com.ar\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/lobosnews.com.ar\/#\/schema\/person\/232422a593d5c541dd9aef6aaed10943","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lobosnews.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/lobosnews.com.ar"],"url":"https:\/\/lobosnews.com.ar\/index.php\/author\/lobos-news\/"}]}},"jetpack_featured_media_url":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/05\/yanina-latorre-revelo-que-wanda-nara-tendria-un-nuevo-novio-famoso-y-mas-joven-que-ella.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/53162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=53162"}],"version-history":[{"count":1,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/53162\/revisions"}],"predecessor-version":[{"id":53164,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/53162\/revisions\/53164"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/media\/53165"}],"wp:attachment":[{"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=53162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=53162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=53162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}