{"id":41544,"date":"2026-03-31T05:55:50","date_gmt":"2026-03-31T05:55:50","guid":{"rendered":"https:\/\/lobosnews.com.ar\/index.php\/2026\/03\/31\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad\/"},"modified":"2026-03-31T10:47:30","modified_gmt":"2026-03-31T10:47:30","slug":"el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad","status":"publish","type":"post","link":"https:\/\/lobosnews.com.ar\/index.php\/2026\/03\/31\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad\/","title":{"rendered":"El Gobierno de Bolivia reemplaz\u00f3 al presidente de YPFB y anunci\u00f3 medidas ante la crisis por combustible de baja calidad"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/03\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad.jpg\" alt=\"El Gobierno de Bolivia reemplaz\u00f3 al presidente de YPFB y anunci\u00f3 medidas ante la crisis por combustible de baja calidad\" height=\"1374\" width=\"2126\"\/><\/p>\n<p>El Gobierno del presidente boliviano, <b>Rodrigo Paz<\/b>, resolvi\u00f3 este lunes relevar al presidente de la estatal Yacimientos Petrol\u00edferos Fiscales Bolivianos (YPFB), <b>Yussef Akly<\/b>, y designar en su lugar a <b>Claudia Cronenbold<\/b>, en medio de una creciente crisis por la calidad del combustible que se comercializa en el pa\u00eds y tras protestas de transportistas en las principales ciudades.<\/p>\n<p>El mandatario tom\u00f3 juramento a Cronenbold en un acto en La Paz, poco despu\u00e9s de que el ministro de Hidrocarburos y Energ\u00edas, Mauricio Medinaceli, comunic\u00f3 el cambio en la conducci\u00f3n de la empresa estatal junto con un paquete de medidas orientadas a garantizar el abastecimiento de carburantes y responder a los reclamos de usuarios afectados. Paz agradeci\u00f3 a Akly por su labor en esta \u201cprimera etapa\u201d desde el cambio de Gobierno en noviembre pasado y destac\u00f3 la trayectoria de su sucesora. \u201cPor apostar por el pa\u00eds como siempre lo ha hecho en su carrera profesional\u201d, expres\u00f3 al dirigirse a la nueva titular de la compa\u00f1\u00eda.<\/p>\n<p>El jefe de Estado afirm\u00f3 que la designaci\u00f3n marca el inicio de \u201cun segundo tiempo para YPFB\u201d con nuevos objetivos estrat\u00e9gicos. Entre ellos, mencion\u00f3 la aspiraci\u00f3n de que Bolivia produzca su propia gasolina y que la empresa recupere su papel como una compa\u00f1\u00eda \u201cpujante\u201d. En ese marco, remarc\u00f3 la necesidad de enfrentar irregularidades dentro de la estatal. \u201c<b>Estaremos firmes para respaldar toda la lucha que sabemos va a ser muy dura contra la corrupci\u00f3n que hay en la estatal, para recuperar una empresa estatal para los bolivianos y que deje de ser una empresa de unos cuantos grupos de poder<\/b>\u201d, sostuvo.<\/p>\n<p>Por su parte, Cronenbold expres\u00f3 su compromiso al asumir el cargo y subray\u00f3 la relevancia de la empresa dentro del esquema energ\u00e9tico del pa\u00eds. <b>\u201cTotal compromiso y dedicaci\u00f3n\u201d<\/b> <b>para hacer \u201cun buen papel en una empresa estrat\u00e9gica y muy importante\u201d<\/b>, declar\u00f3. La funcionaria se convierte en la segunda mujer en liderar YPFB, despu\u00e9s de la designaci\u00f3n de Katya Diederich en octubre de 2020 durante el Gobierno interino de Jeanine \u00c1\u00f1ez.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/03\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad-1.jpg\" alt=\"El Gobierno del presidente boliviano, Rodrigo Paz, resolvi\u00f3 este lunes relevar al presidente de la estatal Yacimientos Petrol\u00edferos Fiscales Bolivianos (YPFB), Yussef Akly, y designar en su lugar a Claudia Cronenbold (AP)\" height=\"5464\" width=\"8192\"\/><\/p>\n<p>Antes del acto, el ministro Medinaceli destac\u00f3 ante la prensa la experiencia de m\u00e1s de dos d\u00e9cadas de Cronenbold en el sector y la defini\u00f3 como un \u201cejemplo de liderazgo femenino en una industria estrat\u00e9gica\u201d. Adem\u00e1s del cambio en la conducci\u00f3n, el funcionario anunci\u00f3 una serie de decisiones orientadas a resolver la crisis por la calidad del combustible.<\/p>\n<p>Entre las principales medidas, Medinaceli inform\u00f3 que el Gobierno firmar\u00e1 nuevos contratos \u201cy con m\u00e1s variados proveedores de gasolina de mayor octanaje sin modificar el precio\u201d. Tambi\u00e9n indic\u00f3 que la Agencia Nacional de Hidrocarburos (<b>ANH<\/b>) organizar\u00e1 un cronograma de limpieza de tanques en todas las estaciones de servicio del pa\u00eds, con el objetivo de garantizar el abastecimiento continuo. Seg\u00fan explic\u00f3, el plan se ejecutar\u00e1 mediante un calendario <b>\u201cque garantice el abastecimiento sin suspenderlo en ninguna zona del pa\u00eds\u201d<\/b>.<\/p>\n<p>El ministro agreg\u00f3 que se \u201cacelerar\u00e1\u201d el resarcimiento estatal a los propietarios de veh\u00edculos que denunciaron da\u00f1os en sus motores por el uso de combustible contaminado. Asimismo, anunci\u00f3 que se impulsar\u00e1 la instalaci\u00f3n de equipos de conversi\u00f3n a gas natural vehicular (GNV) tanto en el transporte p\u00fablico como en el privado, con el fin de reducir la dependencia de combustibles l\u00edquidos.<\/p>\n<p>El paquete incluye adem\u00e1s la aprobaci\u00f3n de un decreto que habilita la importaci\u00f3n de veh\u00edculos que funcionan con di\u00e9sel \u201cde menos de 4.000 de cilindrada\u201d, as\u00ed como la creaci\u00f3n de un \u201cequipo de supervisi\u00f3n permanente de hidrocarburos\u201d para reforzar los controles sobre la cadena de suministro.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/03\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad-2.jpg\" alt=\"La semana pasada, sindicatos de transportistas de La Paz y El Alto realizaron un paro con bloqueos durante dos d\u00edas (Foto: YPFB \/Bolpress)\" height=\"1080\" width=\"1920\"\/><\/p>\n<p>Las decisiones del Ejecutivo se producen tras meses de denuncias de usuarios que reportaron fallas mec\u00e1nicas vinculadas a la calidad de la gasolina. De acuerdo con la propia YPFB, el combustible present\u00f3 niveles elevados de goma y manganeso. <b>La situaci\u00f3n gener\u00f3 protestas en distintos puntos del pa\u00eds<\/b>.<\/p>\n<p>La semana pasada, sindicatos de transportistas de La Paz y El Alto realizaron un paro con bloqueos durante dos d\u00edas, en reclamo por la calidad del carburante y para exigir una compensaci\u00f3n m\u00e1s \u00e1gil por los da\u00f1os sufridos. Las manifestaciones intensificaron la presi\u00f3n sobre el Gobierno para adoptar medidas inmediatas.<\/p>\n<p>Seg\u00fan datos oficiales, Bolivia depende en gran medida de las importaciones para abastecer su mercado interno, con casi el 100 % del di\u00e9sel y alrededor del 60 % de la gasolina provenientes de pa\u00edses como Argentina, Chile, Per\u00fa, Paraguay y Estados Unidos. En ese contexto, el Gobierno busca estabilizar el suministro y recuperar la confianza de los consumidores tras la crisis.<\/p>\n<p><i>(Con informaci\u00f3n de EFE)<\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno del presidente boliviano, Rodrigo Paz, resolvi\u00f3 este lunes relevar al presidente de la estatal Yacimientos Petrol\u00edferos Fiscales Bolivianos (YPFB), Yussef Akly, y designar en su lugar a Claudia Cronenbold, en medio de una creciente crisis por la calidad del combustible que se comercializa en el pa\u00eds y tras protestas de transportistas en las&#8230;<\/p>\n","protected":false},"author":1,"featured_media":41549,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[31],"tags":[],"class_list":["post-41544","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"magazineBlocksPostFeaturedMedia":{"thumbnail":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/03\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad-4-150x150.jpg","medium":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/03\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad-4-300x169.jpg","medium_large":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/03\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad-4-768x432.jpg","large":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/03\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad-4-1024x576.jpg","1536x1536":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/03\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad-4-1536x864.jpg","2048x2048":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/03\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad-4.jpg","newsmatic-featured":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/03\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad-4-820x545.jpg","newsmatic-list":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/03\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad-4-600x400.jpg","newsmatic-thumb":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/03\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad-4-300x200.jpg","newsmatic-small":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/03\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad-4-150x95.jpg","newsmatic-grid":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/03\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad-4-400x250.jpg"},"magazineBlocksPostAuthor":{"name":"admin","avatar":"https:\/\/secure.gravatar.com\/avatar\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":"0","magazineBlocksPostExcerpt":"El Gobierno del presidente boliviano, Rodrigo Paz, resolvi\u00f3 este lunes relevar al presidente de la estatal Yacimientos Petrol\u00edferos Fiscales Bolivianos (YPFB), Yussef Akly, y designar en su lugar a Claudia Cronenbold, en medio de una creciente crisis por la calidad del combustible que se comercializa en el pa\u00eds y tras protestas de transportistas en las...","magazineBlocksPostCategories":["Actualidad"],"magazineBlocksPostViewCount":176,"magazineBlocksPostReadTime":4,"magazine_blocks_featured_image_url":{"full":["https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/03\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad-4.jpg",1920,1080,false],"medium":["https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/03\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad-4-300x169.jpg",300,169,true],"thumbnail":["https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/03\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad-4-150x150.jpg",150,150,true]},"magazine_blocks_author":{"display_name":"admin","author_link":"https:\/\/lobosnews.com.ar\/index.php\/author\/lobos-news\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-31\">Actualidad<\/a>","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Gobierno de Bolivia reemplaz\u00f3 al presidente de YPFB y anunci\u00f3 medidas ante la crisis por combustible de baja calidad - Lobos News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lobosnews.com.ar\/index.php\/2026\/03\/31\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Gobierno de Bolivia reemplaz\u00f3 al presidente de YPFB y anunci\u00f3 medidas ante la crisis por combustible de baja calidad - Lobos News\" \/>\n<meta property=\"og:description\" content=\"El Gobierno del presidente boliviano, Rodrigo Paz, resolvi\u00f3 este lunes relevar al presidente de la estatal Yacimientos Petrol\u00edferos Fiscales Bolivianos (YPFB), Yussef Akly, y designar en su lugar a Claudia Cronenbold, en medio de una creciente crisis por la calidad del combustible que se comercializa en el pa\u00eds y tras protestas de transportistas en las...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lobosnews.com.ar\/index.php\/2026\/03\/31\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Lobos News\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-31T05:55:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-31T10:47:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/03\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad.jpg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/index.php\\\/2026\\\/03\\\/31\\\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/index.php\\\/2026\\\/03\\\/31\\\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/#\\\/schema\\\/person\\\/232422a593d5c541dd9aef6aaed10943\"},\"headline\":\"El Gobierno de Bolivia reemplaz\u00f3 al presidente de YPFB y anunci\u00f3 medidas ante la crisis por combustible de baja calidad\",\"datePublished\":\"2026-03-31T05:55:50+00:00\",\"dateModified\":\"2026-03-31T10:47:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/index.php\\\/2026\\\/03\\\/31\\\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad\\\/\"},\"wordCount\":805,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/index.php\\\/2026\\\/03\\\/31\\\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lobosnews.com.ar\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad-4.jpg\",\"articleSection\":[\"Actualidad\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lobosnews.com.ar\\\/index.php\\\/2026\\\/03\\\/31\\\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/index.php\\\/2026\\\/03\\\/31\\\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad\\\/\",\"url\":\"https:\\\/\\\/lobosnews.com.ar\\\/index.php\\\/2026\\\/03\\\/31\\\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad\\\/\",\"name\":\"El Gobierno de Bolivia reemplaz\u00f3 al presidente de YPFB y anunci\u00f3 medidas ante la crisis por combustible de baja calidad - Lobos News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/index.php\\\/2026\\\/03\\\/31\\\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/index.php\\\/2026\\\/03\\\/31\\\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lobosnews.com.ar\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad-4.jpg\",\"datePublished\":\"2026-03-31T05:55:50+00:00\",\"dateModified\":\"2026-03-31T10:47:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/index.php\\\/2026\\\/03\\\/31\\\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lobosnews.com.ar\\\/index.php\\\/2026\\\/03\\\/31\\\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/index.php\\\/2026\\\/03\\\/31\\\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lobosnews.com.ar\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad-4.jpg\",\"contentUrl\":\"https:\\\/\\\/lobosnews.com.ar\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad-4.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"El Gobierno de Bolivia reemplaz\u00f3 al presidente de YPFB y anunci\u00f3 medidas ante la crisis por combustible de baja calidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/index.php\\\/2026\\\/03\\\/31\\\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/lobosnews.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Gobierno de Bolivia reemplaz\u00f3 al presidente de YPFB y anunci\u00f3 medidas ante la crisis por combustible de baja calidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/lobosnews.com.ar\\\/\",\"name\":\"Lobos News\",\"description\":\"Informaci\u00f3n a cada instante\",\"publisher\":{\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lobosnews.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/#organization\",\"name\":\"Lobos News\",\"url\":\"https:\\\/\\\/lobosnews.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lobosnews.com.ar\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logo-lobosnews.png\",\"contentUrl\":\"https:\\\/\\\/lobosnews.com.ar\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logo-lobosnews.png\",\"width\":500,\"height\":200,\"caption\":\"Lobos News\"},\"image\":{\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lobosnews.com.ar\\\/#\\\/schema\\\/person\\\/232422a593d5c541dd9aef6aaed10943\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/lobosnews.com.ar\"],\"url\":\"https:\\\/\\\/lobosnews.com.ar\\\/index.php\\\/author\\\/lobos-news\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Gobierno de Bolivia reemplaz\u00f3 al presidente de YPFB y anunci\u00f3 medidas ante la crisis por combustible de baja calidad - Lobos News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lobosnews.com.ar\/index.php\/2026\/03\/31\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad\/","og_locale":"es_ES","og_type":"article","og_title":"El Gobierno de Bolivia reemplaz\u00f3 al presidente de YPFB y anunci\u00f3 medidas ante la crisis por combustible de baja calidad - Lobos News","og_description":"El Gobierno del presidente boliviano, Rodrigo Paz, resolvi\u00f3 este lunes relevar al presidente de la estatal Yacimientos Petrol\u00edferos Fiscales Bolivianos (YPFB), Yussef Akly, y designar en su lugar a Claudia Cronenbold, en medio de una creciente crisis por la calidad del combustible que se comercializa en el pa\u00eds y tras protestas de transportistas en las...","og_url":"https:\/\/lobosnews.com.ar\/index.php\/2026\/03\/31\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad\/","og_site_name":"Lobos News","article_published_time":"2026-03-31T05:55:50+00:00","article_modified_time":"2026-03-31T10:47:30+00:00","og_image":[{"url":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/03\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad.jpg","type":"","width":"","height":""}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/03\/31\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad\/#article","isPartOf":{"@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/03\/31\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad\/"},"author":{"name":"admin","@id":"https:\/\/lobosnews.com.ar\/#\/schema\/person\/232422a593d5c541dd9aef6aaed10943"},"headline":"El Gobierno de Bolivia reemplaz\u00f3 al presidente de YPFB y anunci\u00f3 medidas ante la crisis por combustible de baja calidad","datePublished":"2026-03-31T05:55:50+00:00","dateModified":"2026-03-31T10:47:30+00:00","mainEntityOfPage":{"@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/03\/31\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad\/"},"wordCount":805,"commentCount":0,"publisher":{"@id":"https:\/\/lobosnews.com.ar\/#organization"},"image":{"@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/03\/31\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad\/#primaryimage"},"thumbnailUrl":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/03\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad-4.jpg","articleSection":["Actualidad"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lobosnews.com.ar\/index.php\/2026\/03\/31\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/03\/31\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad\/","url":"https:\/\/lobosnews.com.ar\/index.php\/2026\/03\/31\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad\/","name":"El Gobierno de Bolivia reemplaz\u00f3 al presidente de YPFB y anunci\u00f3 medidas ante la crisis por combustible de baja calidad - Lobos News","isPartOf":{"@id":"https:\/\/lobosnews.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/03\/31\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad\/#primaryimage"},"image":{"@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/03\/31\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad\/#primaryimage"},"thumbnailUrl":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/03\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad-4.jpg","datePublished":"2026-03-31T05:55:50+00:00","dateModified":"2026-03-31T10:47:30+00:00","breadcrumb":{"@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/03\/31\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lobosnews.com.ar\/index.php\/2026\/03\/31\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/03\/31\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad\/#primaryimage","url":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/03\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad-4.jpg","contentUrl":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/03\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad-4.jpg","width":1920,"height":1080,"caption":"El Gobierno de Bolivia reemplaz\u00f3 al presidente de YPFB y anunci\u00f3 medidas ante la crisis por combustible de baja calidad"},{"@type":"BreadcrumbList","@id":"https:\/\/lobosnews.com.ar\/index.php\/2026\/03\/31\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lobosnews.com.ar\/"},{"@type":"ListItem","position":2,"name":"El Gobierno de Bolivia reemplaz\u00f3 al presidente de YPFB y anunci\u00f3 medidas ante la crisis por combustible de baja calidad"}]},{"@type":"WebSite","@id":"https:\/\/lobosnews.com.ar\/#website","url":"https:\/\/lobosnews.com.ar\/","name":"Lobos News","description":"Informaci\u00f3n a cada instante","publisher":{"@id":"https:\/\/lobosnews.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lobosnews.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/lobosnews.com.ar\/#organization","name":"Lobos News","url":"https:\/\/lobosnews.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lobosnews.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/01\/logo-lobosnews.png","contentUrl":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/01\/logo-lobosnews.png","width":500,"height":200,"caption":"Lobos News"},"image":{"@id":"https:\/\/lobosnews.com.ar\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/lobosnews.com.ar\/#\/schema\/person\/232422a593d5c541dd9aef6aaed10943","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/76e419471a2083bc3ceab22a763dbbf9b0c1bd15a6214cf3280e2c2dde4580f9?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/lobosnews.com.ar"],"url":"https:\/\/lobosnews.com.ar\/index.php\/author\/lobos-news\/"}]}},"jetpack_featured_media_url":"https:\/\/lobosnews.com.ar\/wp-content\/uploads\/2026\/03\/el-gobierno-de-bolivia-reemplazo-al-presidente-de-ypfb-y-anuncio-medidas-ante-la-crisis-por-combustible-de-baja-calidad-4.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/41544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=41544"}],"version-history":[{"count":1,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/41544\/revisions"}],"predecessor-version":[{"id":41548,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/41544\/revisions\/41548"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/media\/41549"}],"wp:attachment":[{"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=41544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=41544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lobosnews.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=41544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}